{"id":13076,"date":"2009-06-01T17:44:07","date_gmt":"2009-06-01T20:44:07","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2009\/06\/01\/operacao-casa-nova\/"},"modified":"2023-07-13T17:52:17","modified_gmt":"2023-07-13T20:52:17","slug":"operacao-casa-nova","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/operacao-casa-nova\/","title":{"rendered":"Opera\u00e7\u00e3o Casa Nova"},"content":{"rendered":"<p style=\"text-align: justify;\">Ap\u00f3s a inaugura\u00e7\u00e3o do novo Pres\u00eddio de Rio do Sul, o DEAP desencadeou neste final de semana a &#8220;OPERA\u00c7\u00c3O CASA NOVA&#8221;, com o objetivo de transferir os 210 detentos do Pres\u00eddio antigo para as novas instala\u00e7\u00f5es. Mais de cinquenta (50) Agentes Prisionais estiveram envolvidos na opera\u00e7\u00e3o, que transcorrreu em clima de tranquilidade e contou com o apoio da Guarda Municipal daquela cidade. A equipe do DEAP permaneceu na cidade de Rio do Sul at\u00e9 domingo de prontid\u00e3o. A nova obra custou aos cofres p\u00fablicos mais de 4 milh\u00f5es de reais.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a inaugura\u00e7\u00e3o do novo Pres\u00eddio de Rio do Sul, o DEAP desencadeou neste final de semana a &#8220;OPERA\u00c7\u00c3O CASA NOVA&#8221;, com o objetivo de transferir os 210 detentos do Pres\u00eddio antigo para as novas instala\u00e7\u00f5es. Mais de cinquenta (50) Agentes Prisionais estiveram envolvidos na opera\u00e7\u00e3o, que transcorrreu em clima de tranquilidade e contou com [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:56:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13076"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13076"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/14289"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}