{"id":13124,"date":"2010-12-08T00:00:20","date_gmt":"2010-12-08T02:00:20","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2010\/12\/08\/inaugurada-a-fabrica-de-estofados-na-penitenciaria-de-curitibanos\/"},"modified":"2023-07-13T17:52:04","modified_gmt":"2023-07-13T20:52:04","slug":"inaugurada-a-fabrica-de-estofados-na-penitenciaria-de-curitibanos","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/inaugurada-a-fabrica-de-estofados-na-penitenciaria-de-curitibanos\/","title":{"rendered":"Inaugurada a f\u00e1brica de estofados na Penitenci\u00e1ria de Curitibanos"},"content":{"rendered":"<p style=\"text-align: justify;\">Na ter\u00e7a-feira, 30\/11, na Penitenci\u00e1ria da Regi\u00e3o de Curitibanos foi inaugurada a f\u00e1brica de estofados Catarina, fruto de uma parceria entre a SSP\/SJC atrav\u00e9s do DEAP e a Rede Catarinense de M\u00f3veis e Eletrodom\u00e9sticos Berlanda. Participaram da inaugura\u00e7\u00e3o o Diretor do Departamento de Administra\u00e7\u00e3o Prisional, Sr. Ad\u00e9rcio Jos\u00e9 Velter, o Diretor do Grupo Berlanda, Sr. Nilso Berlanda, o Diretor da Penitenci\u00e1ria da Regi\u00e3o de Curitibanos, Sr. Anderson Santos, o Juiz da Vara de Execu\u00e7\u00f5es Penais, Dr. Marcos Bigolin, al\u00e9m de autoridades regionais e do Governo do Estado de Santa Catarina. Participam do projeto 54 presos, dos regimes fechado e semi-aberto, que a cada tr\u00eas dias de trabalho recebem um dia de redu\u00e7\u00e3o de pena. Toda a produ\u00e7\u00e3o \u00e9 vendida nas 137 lojas do grupo Berlanda, em Santa Catarina e no Rio Grande do Sul. A iniciativa partiu do empres\u00e1rio Nilso Berlanda e da Secretaria de Desenvolvimento Regional (SDR) de Curitibanos, em 2009. \u201cEm visita \u00e0 unidade prisional, verifiquei a oportunidade de contribuir para a ressocializa\u00e7\u00e3o dos apenados. Eles precisam de ocupa\u00e7\u00e3o e a fabrica\u00e7\u00e3o de estofados surgiu como possibilidade de reeduca\u00e7\u00e3o. E o resultado \u00e9 um sucesso absoluto, estamos surpresos com o bom desempenho dos detentos\u201d, detalha o empres\u00e1rio. Todo o investimento com a instala\u00e7\u00e3o da f\u00e1brica, com os maquin\u00e1rios e a compra de mat\u00e9ria-prima, oriunda de Santa Catarina e de outros estados, \u00e9 feito pela Berlanda. \u201cHoje s\u00e3o fabricados tr\u00eas modelos de estofados, e j\u00e1 est\u00e1 previsto o lan\u00e7amento de outras seis linhas para janeiro de 2011. Para esta \u00e9poca, a estimativa ser\u00e1 de uma produ\u00e7\u00e3o de 900 jogos ao m\u00eas, com o envolvimento de mais detentos\u201d, calcula David Casagrande, coordenador de ind\u00fastria da Catarina. O Diretor do DEAP, Ad\u00e9rcio Velter destacou a import\u00e2ncia do projeto na ressocializa\u00e7\u00e3o dos detentos e prepara\u00e7\u00e3o para o retorno a sociedade, pois o trabalho gera a expectativa de um futuro melhor.<\/p>","protected":false},"excerpt":{"rendered":"<p>Na ter\u00e7a-feira, 30\/11, na Penitenci\u00e1ria da Regi\u00e3o de Curitibanos foi inaugurada a f\u00e1brica de estofados Catarina, fruto de uma parceria entre a SSP\/SJC atrav\u00e9s do DEAP e a Rede Catarinense de M\u00f3veis e Eletrodom\u00e9sticos Berlanda. Participaram da inaugura\u00e7\u00e3o o Diretor do Departamento de Administra\u00e7\u00e3o Prisional, Sr. Ad\u00e9rcio Jos\u00e9 Velter, o Diretor do Grupo Berlanda, Sr. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:49:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13124"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13124"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/14179"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}