{"id":22089,"date":"2025-08-25T17:05:43","date_gmt":"2025-08-25T20:05:43","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=22089"},"modified":"2025-08-25T17:05:43","modified_gmt":"2025-08-25T20:05:43","slug":"policia-penal-renova-adesao-a-ficco-sc","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/policia-penal-renova-adesao-a-ficco-sc\/","title":{"rendered":"Pol\u00edcia Penal renova ades\u00e3o \u00e0 FICCO-SC"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Na tarde desta segunda-feira, 25 de agosto, foi realizada, no audit\u00f3rio da Pol\u00edcia Federal, em Florian\u00f3polis, a solenidade de assinatura do acordo de ades\u00e3o \u00e0 For\u00e7a Integrada de Combate ao Crime Organizado no Estado de Santa Catarina (FICCO-SC). O evento refor\u00e7ou o compromisso das institui\u00e7\u00f5es de seguran\u00e7a p\u00fablica catarinenses com o enfrentamento \u00e0s organiza\u00e7\u00f5es criminosas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A Pol\u00edcia Penal de Santa Catarina, que j\u00e1 integra a FICCO-SC desde sua cria\u00e7\u00e3o, ao lado da Pol\u00edcia Civil, foi uma das entidades signat\u00e1rias desta nova etapa de coopera\u00e7\u00e3o t\u00e9cnica. Sua atua\u00e7\u00e3o vem sendo fundamental em opera\u00e7\u00f5es conjuntas, como a Opera\u00e7\u00e3o COLAPSO, deflagrada em 10 de junho de 2025, quando cumpriu mandados de pris\u00e3o e deteve suspeitos ligados a fac\u00e7\u00f5es criminosas em v\u00e1rias regi\u00f5es do estado.<\/span><\/p>\n<figure id=\"attachment_22091\" aria-describedby=\"caption-attachment-22091\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-16.44.23.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-22091\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-16.44.23-1024x593.jpeg\" alt=\"\" width=\"696\" height=\"403\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-16.44.23-1024x593.jpeg 1024w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-16.44.23-300x174.jpeg 300w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-16.44.23-768x445.jpeg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-16.44.23-1536x889.jpeg 1536w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-16.44.23-2048x1186.jpeg 2048w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><figcaption id=\"caption-attachment-22091\" class=\"wp-caption-text\">Foto: Jaqueline Noceti\/SEJURI<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Com o Novo Acordo de Coopera\u00e7\u00e3o T\u00e9cnica, a For\u00e7a Integrada de Combate ao Crime Organizado (FICCO-SC) passou a contar tamb\u00e9m com a Pol\u00edcia Militar de Santa Catarina (PMSC) e a Secretaria Nacional de Pol\u00edticas Penais (Senappen).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A partir de agora, a for\u00e7a-tarefa \u00e9 composta pela Pol\u00edcia Federal, Secretaria Nacional de Pol\u00edticas Penais (Senappen), Pol\u00edcia Penal de Santa Catarina (PPEN-SC), Pol\u00edcia Civil de Santa Catarina (PCSC) e Pol\u00edcia Militar de Santa Catarina (PMSC), fortalecendo ainda mais a integra\u00e7\u00e3o entre os \u00f3rg\u00e3os de seguran\u00e7a no combate \u00e0s organiza\u00e7\u00f5es criminosas no estado.<\/span><\/p>\n<figure id=\"attachment_22092\" aria-describedby=\"caption-attachment-22092\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/08\/FOT_0267-scaled.jpg\"><img decoding=\"async\" class=\"size-large wp-image-22092\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/08\/FOT_0267-1024x685.jpg\" alt=\"\" width=\"696\" height=\"466\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/FOT_0267-1024x685.jpg 1024w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/FOT_0267-300x201.jpg 300w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/FOT_0267-768x513.jpg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/FOT_0267-1536x1027.jpg 1536w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/08\/FOT_0267-2048x1369.jpg 2048w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><figcaption id=\"caption-attachment-22092\" class=\"wp-caption-text\">Foto: Policia Federal\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A secret\u00e1ria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, <\/span>Daniele Amorim<span style=\"font-weight: 400;\">, destacou a import\u00e2ncia da uni\u00e3o entre as for\u00e7as de seguran\u00e7a. <\/span><i><span style=\"font-weight: 400;\">\u201cO combate ao crime organizado exige integra\u00e7\u00e3o, estrat\u00e9gia e uni\u00e3o de esfor\u00e7os. A presen\u00e7a da Pol\u00edcia Penal desde o in\u00edcio da FICCO-SC demonstra a relev\u00e2ncia da atua\u00e7\u00e3o do sistema prisional nesse enfrentamento, e a ades\u00e3o de novos \u00f3rg\u00e3os s\u00f3 fortalece nossa capacidade de resposta contra as organiza\u00e7\u00f5es criminosas em Santa Catarina\u201d,<\/span><\/i><span style=\"font-weight: 400;\"> afirmou.<\/span><\/p>\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Na tarde desta segunda-feira, 25 de agosto, foi realizada, no audit\u00f3rio da Pol\u00edcia Federal, em Florian\u00f3polis, a solenidade de assinatura do acordo de ades\u00e3o \u00e0 For\u00e7a Integrada de Combate ao Crime Organizado no Estado de Santa Catarina (FICCO-SC). O evento refor\u00e7ou o compromisso das institui\u00e7\u00f5es de seguran\u00e7a p\u00fablica catarinenses com o enfrentamento \u00e0s organiza\u00e7\u00f5es criminosas. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":22090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:06:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22089"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=22089"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/22090"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=22089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=22089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=22089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}