{"id":22424,"date":"2025-09-23T18:59:51","date_gmt":"2025-09-23T21:59:51","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=22424"},"modified":"2025-09-23T18:59:51","modified_gmt":"2025-09-23T21:59:51","slug":"reeducandos-do-sistema-prisional-de-blumenau-produzem-100-cobertores-entregues-a-maternidade-do-hospital-regional-de-sao-jose","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/reeducandos-do-sistema-prisional-de-blumenau-produzem-100-cobertores-entregues-a-maternidade-do-hospital-regional-de-sao-jose\/","title":{"rendered":"Reeducandos do sistema prisional de Blumenau produzem 100 cobertores entregues \u00e0 Maternidade do Hospital Regional de S\u00e3o Jos\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\">Nesta ter\u00e7a-feira (23), a Pol\u00edcia Penal de Santa Catarina realizou a entrega de 100 cobertores produzidos por pessoas privadas de liberdade da unidade prisional de Blumenau. O material foi destinado \u00e0 maternidade do Hospital Regional, em um gesto que une solidariedade e ressocializa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">A iniciativa \u00e9 fruto de uma parceria entre a Pol\u00edcia Penal e a empresa HEDRONS, respons\u00e1vel pela doa\u00e7\u00e3o dos insumos utilizados na confec\u00e7\u00e3o das pe\u00e7as. Sob orienta\u00e7\u00e3o, os reeducandos aplicam m\u00e3o de obra para transformar os materiais em cobertores, que agora ir\u00e3o aquecer m\u00e3es e rec\u00e9m-nascidos atendidos pela unidade hospitalar.<\/p>\n<p><a href=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.15.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter  wp-image-22426\" src=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.15-768x1024.jpeg\" alt=\"\" width=\"296\" height=\"395\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.15-768x1024.jpeg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.15-225x300.jpeg 225w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.15-9x12.jpeg 9w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.15.jpeg 960w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">O diretor-geral da Pol\u00edcia Penal de Santa Catarina, que fez a entrega pessoalmente, destacou o impacto social da a\u00e7\u00e3o. \u201cEsse tipo de projeto mostra que o sistema prisional pode ser uma ferramenta de transforma\u00e7\u00e3o. Ao mesmo tempo em que os internos aprendem um of\u00edcio e exercitam valores de solidariedade, a comunidade tamb\u00e9m \u00e9 beneficiada\u201d, afirmou.<\/p>\n<p>&#8220;A parceria entre a Secretaria da Sa\u00fade e a Secretaria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social representa uma importante pol\u00edtica p\u00fablica de inclus\u00e3o. A iniciativa traz benef\u00edcios n\u00e3o apenas para os apenados, que encontram na capacita\u00e7\u00e3o uma nova oportunidade de vida, mas tamb\u00e9m para a sociedade, que se beneficia com esse trabalho. Trata-se de uma a\u00e7\u00e3o que promove dignidade, reduz a reincid\u00eancia e reafirma o compromisso do Estado com a justi\u00e7a social e com a sa\u00fade&#8221;, destaca o Secret\u00e1rio de Estado da Sa\u00fade, Diogo Demarchi.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de contribuir para o acolhimento das fam\u00edlias na maternidade, o projeto refor\u00e7a a pol\u00edtica de valoriza\u00e7\u00e3o do trabalho prisional como instrumento de reintegra\u00e7\u00e3o social, possibilitando que os custodiados desenvolvam novas habilidades e enxerguem perspectivas para o futuro.<\/p>\n<p><a href=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.17.jpeg\"><img decoding=\"async\" class=\"aligncenter  wp-image-22427\" src=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.17-768x1024.jpeg\" alt=\"\" width=\"335\" height=\"446\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.17-768x1024.jpeg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.17-225x300.jpeg 225w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.17-9x12.jpeg 9w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-23-at-18.11.17.jpeg 960w\" sizes=\"(max-width: 335px) 100vw, 335px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Nesta ter\u00e7a-feira (23), a Pol\u00edcia Penal de Santa Catarina realizou a entrega de 100 cobertores produzidos por pessoas privadas de liberdade da unidade prisional de Blumenau. O material foi destinado \u00e0 maternidade do Hospital Regional, em um gesto que une solidariedade e ressocializa\u00e7\u00e3o. A iniciativa \u00e9 fruto de uma parceria entre a Pol\u00edcia Penal e [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":22425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:02:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22424"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=22424"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/22425"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=22424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=22424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=22424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}