{"id":23384,"date":"2025-12-03T11:08:22","date_gmt":"2025-12-03T14:08:22","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=23384"},"modified":"2025-12-03T11:08:22","modified_gmt":"2025-12-03T14:08:22","slug":"visita-do-cnj-a-sejuri-destaca-politicas-laborais-e-modelo-catarinense-de-ressocializacao","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/visita-do-cnj-a-sejuri-destaca-politicas-laborais-e-modelo-catarinense-de-ressocializacao\/","title":{"rendered":"Visita do CNJ \u00e0 Sejuri destaca pol\u00edticas laborais e modelo catarinense de ressocializa\u00e7\u00e3o"},"content":{"rendered":"<p>A Secretaria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social recebeu, nesta ter\u00e7a-feira, a visita do desembargador Lanfredi, coordenador do Departamento de Monitoramento e Fiscaliza\u00e7\u00e3o do Sistema Carcer\u00e1rio (DMF\/CNJ); da dra. Solange, ju\u00edza auxiliar do Conselho Nacional de Justi\u00e7a; do dr. Ricardo, juiz auxiliar do CNJ; al\u00e9m de outros ju\u00edzes auxiliares da Presid\u00eancia do Conselho. A comitiva esteve na Sejuri para conhecer de perto as pol\u00edticas laborais desenvolvidas pelo Estado e o funcionamento dos fundos rotativos regionais do sistema penitenci\u00e1rio catarinense.<\/p>\n<p>Durante a reuni\u00e3o, a secret\u00e1ria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Danielle Amorim Silva, apresentou a estrutura atual da Sejuri e fez um panorama completo do sistema prisional e socioeducativo de Santa Catarina, que hoje conta com 54 unidades. Ela detalhou os programas de ressocializa\u00e7\u00e3o por meio do trabalho e do estudo, explicou a rotina operacional das unidades e destacou o papel essencial dos policiais penais que atuam na ponta.<\/p>\n<p>Tamb\u00e9m participou da agenda o F\u00e1bio Roberto Ramos, coordenador de Trabalho e Renda da Sejuri, que apresentou o modelo laboral catarinense e falou sobre a organiza\u00e7\u00e3o das frentes de trabalho dentro das unidades, a parceria com empresas e o impacto dos fundos rotativos regionais na manuten\u00e7\u00e3o e amplia\u00e7\u00e3o das atividades produtivas.<\/p>\n<p>Para a secret\u00e1ria Danielle Amorim, o encontro refor\u00e7a o compromisso catarinense com uma pol\u00edtica penitenci\u00e1ria moderna, eficaz e voltada \u00e0 reintegra\u00e7\u00e3o social.<\/p>\n<p>\u201cSanta Catarina tem investido de forma cont\u00ednua em trabalho, educa\u00e7\u00e3o, no policial penal e na organiza\u00e7\u00e3o interna das unidades. Nosso objetivo \u00e9 garantir seguran\u00e7a, dignidade e oportunidades reais de reintegra\u00e7\u00e3o, valorizando o trabalho essencial dos policiais penais e fortalecendo as pol\u00edticas p\u00fablicas do sistema prisional e socioeducativo\u201d, afirmou.<\/p>\n<p>A visita encerrou com a sinaliza\u00e7\u00e3o de novas parcerias e trocas t\u00e9cnicas com o CNJ, ampliando o di\u00e1logo institucional sobre gest\u00e3o, inova\u00e7\u00e3o e ressocializa\u00e7\u00e3o no sistema prisional brasileiro.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-23386\" src=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/12\/DSC_0848-5-1024x683.jpg\" alt=\"\" width=\"696\" height=\"464\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/12\/DSC_0848-5-1024x683.jpg 1024w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/12\/DSC_0848-5-300x200.jpg 300w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/12\/DSC_0848-5-768x512.jpg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/12\/DSC_0848-5-1536x1024.jpg 1536w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/12\/DSC_0848-5-2048x1365.jpg 2048w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2025\/12\/DSC_0848-5-18x12.jpg 18w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>Foto: Jaqueline Noceti\/SEJURI<\/p>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social recebeu, nesta ter\u00e7a-feira, a visita do desembargador Lanfredi, coordenador do Departamento de Monitoramento e Fiscaliza\u00e7\u00e3o do Sistema Carcer\u00e1rio (DMF\/CNJ); da dra. Solange, ju\u00edza auxiliar do Conselho Nacional de Justi\u00e7a; do dr. Ricardo, juiz auxiliar do CNJ; al\u00e9m de outros ju\u00edzes auxiliares da Presid\u00eancia do Conselho. A comitiva esteve [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":23385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:13:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23384"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=23384"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/23385"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=23384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=23384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=23384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}