{"id":23927,"date":"2026-02-06T12:08:21","date_gmt":"2026-02-06T15:08:21","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=23927"},"modified":"2026-02-06T12:08:21","modified_gmt":"2026-02-06T15:08:21","slug":"aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade\/","title":{"rendered":"\u00c1guia de Osso: curso que nasceu na estrada e transformou Santa Catarina em refer\u00eancia nacional em escolta de alta complexidade"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Muito antes de se consolidar como uma das forma\u00e7\u00f5es mais respeitadas do sistema prisional brasileiro, o Curso Avan\u00e7ado \u00c1guia de Osso nasceu da busca incans\u00e1vel por conhecimento. Em 2016, quando a primeira turma foi formada, n\u00e3o havia uma doutrina pronta de escolta de alta complexidade dentro da Pol\u00edcia Penal catarinense. Ela precisou ser constru\u00edda passo a passo, estado por estado.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">O curso teve in\u00edcio em Florian\u00f3polis, mas rapidamente ganhou a estrada. Os alunos realizaram diversos m\u00f3dulos onde percorreram diferentes cidades e institui\u00e7\u00f5es especializadas para compreender, na pr\u00e1tica, como operavam as principais for\u00e7as do pa\u00eds. O roteiro incluiu passagens pelo Rio de Janeiro, Blumenau e Curitiba, al\u00e9m de visitas t\u00e9cnicas Visitas t\u00e9cnicas ao Grupamento de Interven\u00e7\u00e3o T\u00e1tica (GIT\/RJ); \u00e0 Coordenadoria de Opera\u00e7\u00f5es Especiais da Pol\u00edcia Civil (CORE\/RJ); ao Centro de Opera\u00e7\u00f5es Policiais Especiais (COPE\/PR); ao T\u00e1tico Integrado de Grupos de Repress\u00e3o Especial (TIGRE\/PR); \u00e0 Pol\u00edcia Rodovi\u00e1ria Federal em Santa Catarina (PRF); ao Grupo de Pronta Interven\u00e7\u00e3o da Pol\u00edcia Federal (GPI\/PR); ao Servi\u00e7o Aeropolicial (SAER) da Pol\u00edcia Civil de Santa Catarina (PCSC); ao Batalh\u00e3o de Opera\u00e7\u00f5es Policiais Especiais da Pol\u00edcia Militar de Santa Catarina (BOPE\/PMSC); ao Ex\u00e9rcito Brasileiro; e a outras unidades de refer\u00eancia nacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada deslocamento tinha um prop\u00f3sito claro: absorver conhecimento diretamente da fonte. Para o Policial Penal Rafael Zaba, diretor do N\u00facleo de Recapturas, que participou da primeira edi\u00e7\u00e3o do curso, o objetivo era buscar a doutrina de escolta de alta complexidade, conhecendo de perto o funcionamento das unidades especializadas. Em cada institui\u00e7\u00e3o, uma especialidade. Algumas eram refer\u00eancia em combate em ambientes confinados (CQB), outras em patrulha urbana ou patrulha rural. O aprendizado era fragmentado, mas estrat\u00e9gico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao longo de um ciclo de forma\u00e7\u00e3o extremamente rigoroso, 21 alunos integraram o curso. Ao final do processo, apenas quatro conclu\u00edram todas as etapas e se formaram, dando origem \u00e0 primeira turma do \u00c1guia de Osso. Um grupo pequeno em n\u00famero, mas decisivo para o futuro da Pol\u00edcia Penal de Santa Catarina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A partir dali, a l\u00f3gica se inverteu. Se no in\u00edcio foi preciso ir atr\u00e1s da doutrina, hoje s\u00e3o outros estados que v\u00eam buscar conhecimento em Santa Catarina. O \u00c1guia de Osso se tornou refer\u00eancia nacional em escolta de alta complexidade, influenciando a forma\u00e7\u00e3o de operadores em todo o pa\u00eds. Ap\u00f3s a consolida\u00e7\u00e3o da doutrina pr\u00f3pria, o curso passou a ter a maior parte de suas instru\u00e7\u00f5es conduzidas pela Pol\u00edcia Penal catarinense, com o apoio de outras for\u00e7as de seguran\u00e7a, como a Pol\u00edcia Militar de Santa Catarina, a Pol\u00edcia Civil de Santa Catarina, o Corpo de Bombeiros Militar e as For\u00e7as Armadas, recebendo profissionais de diferentes estados interessados na metodologia desenvolvida em Santa Catarina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa trajet\u00f3ria de excel\u00eancia explica por que o curso segue sendo um dos mais disputados da \u00e1rea. Em 2026, a Pol\u00edcia Penal de Santa Catarina inicia uma nova edi\u00e7\u00e3o do Curso Avan\u00e7ado \u00c1guia de Osso no dia 5 de fevereiro, no Centro de Treinamento de S\u00e3o Pedro de Alc\u00e2ntara. Ao todo, 44 policiais penais participam da forma\u00e7\u00e3o, que n\u00e3o era realizada desde 2022.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voltado exclusivamente a operadores de escolta de alta complexidade, o curso tem cerca de 45 dias de internato e \u00e9 marcado por um rigor elevado. A exig\u00eancia \u00e9 t\u00e9cnica, f\u00edsica, psicol\u00f3gica e operacional. N\u00e3o se trata de uma capacita\u00e7\u00e3o acess\u00edvel por simples inscri\u00e7\u00e3o. \u00c9 um curso que se conquista.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O n\u00edvel de exig\u00eancia \u00e9 conhecido tamb\u00e9m pela atual secret\u00e1ria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Danielle Amorim. Com mais de duas d\u00e9cadas de atua\u00e7\u00e3o no sistema prisional catarinense, ela traz o \u00c1guia de Osso em seu pr\u00f3prio curr\u00edculo profissional, tendo vivenciado de perto o rigor e a responsabilidade que a forma\u00e7\u00e3o exige.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cO \u00c1guia de Osso representa o mais alto n\u00edvel de dedica\u00e7\u00e3o nas capacita\u00e7\u00f5es da Pol\u00edcia Penal. \u00c9 um curso que exige excel\u00eancia, disciplina e absoluto compromisso com a seguran\u00e7a p\u00fablica\u201d, destaca a secret\u00e1ria\u201d, destaca a secret\u00e1ria Danielle Amorim.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais do que um curso, o \u00c1guia de Osso representa a maturidade operacional da Pol\u00edcia Penal de Santa Catarina. Um projeto que come\u00e7ou com deslocamentos, aprendizado e escuta ativa e que hoje se consolida como s\u00edmbolo de preparo t\u00e9cnico e refer\u00eancia nacional.<br \/>\n<\/span><\/p>\n<div id='gallery-1' class='gallery galleryid-23927 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.sejuri.sc.gov.br\/en\/aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade\/aguia-5\/'><img fetchpriority=\"high\" decoding=\"async\" width=\"272\" height=\"300\" src=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-5-272x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-5-272x300.jpeg 272w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-5-928x1024.jpeg 928w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-5-768x847.jpeg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-5-11x12.jpeg 11w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-5.jpeg 1086w\" sizes=\"(max-width: 272px) 100vw, 272px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sejuri.sc.gov.br\/en\/aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade\/aguia-4\/'><img decoding=\"async\" width=\"300\" height=\"231\" src=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-4-300x231.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-4-300x231.jpeg 300w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-4-16x12.jpeg 16w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-4.jpeg 588w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.sejuri.sc.gov.br\/en\/aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade\/aguia-3\/'><img decoding=\"async\" width=\"252\" height=\"300\" src=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-3-252x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-3-252x300.jpeg 252w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-3-859x1024.jpeg 859w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-3-768x915.jpeg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-3-10x12.jpeg 10w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-3.jpeg 1001w\" sizes=\"(max-width: 252px) 100vw, 252px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sejuri.sc.gov.br\/en\/aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade\/aguia-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-1-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-1-300x300.jpeg 300w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-1-1024x1019.jpeg 1024w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-1-150x150.jpeg 150w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-1-12x12.jpeg 12w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-1.jpeg 1206w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sejuri.sc.gov.br\/en\/aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade\/aguia-7\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"290\" src=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-7-300x290.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-7-300x290.jpeg 300w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-7-1024x988.jpeg 1024w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-7-768x741.jpeg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-7-12x12.jpeg 12w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-7.jpeg 1206w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sejuri.sc.gov.br\/en\/aguia-de-osso-curso-que-nasceu-na-estrada-e-transformou-santa-catarina-em-referencia-nacional-em-escolta-de-alta-complexidade\/aguia-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-6-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-6-300x300.jpeg 300w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-6-1024x1024.jpeg 1024w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-6-150x150.jpeg 150w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-6-768x768.jpeg 768w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-6-12x12.jpeg 12w, https:\/\/www.sejuri.sc.gov.br\/wp-content\/uploads\/2026\/02\/Aguia-6.jpeg 1206w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Muito antes de se consolidar como uma das forma\u00e7\u00f5es mais respeitadas do sistema prisional brasileiro, o Curso Avan\u00e7ado \u00c1guia de Osso nasceu da busca incans\u00e1vel por conhecimento. Em 2016, quando a primeira turma foi formada, n\u00e3o havia uma doutrina pronta de escolta de alta complexidade dentro da Pol\u00edcia Penal catarinense. Ela precisou ser constru\u00edda passo [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":23928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:49:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23927"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=23927"}],"version-history":[{"count":2,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23927\/revisions"}],"predecessor-version":[{"id":23943,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23927\/revisions\/23943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/23928"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=23927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=23927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=23927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}