{"id":24420,"date":"2026-03-24T15:09:05","date_gmt":"2026-03-24T18:09:05","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=24420"},"modified":"2026-03-24T15:09:05","modified_gmt":"2026-03-24T18:09:05","slug":"policia-penal-reforca-atuacao-e-marca-presenca-na-expocacador-2026-com-equipes-especializadas","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/policia-penal-reforca-atuacao-e-marca-presenca-na-expocacador-2026-com-equipes-especializadas\/","title":{"rendered":"Pol\u00edcia Penal refor\u00e7a atua\u00e7\u00e3o e marca presen\u00e7a na ExpoCa\u00e7ador 2026 com equipes especializadas"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><span style=\"font-weight: 400;\">A atua\u00e7\u00e3o cada vez mais moderna, tecnol\u00f3gica e integrada da Pol\u00edcia Penal de Santa Catarina tamb\u00e9m se reflete na presen\u00e7a em grandes eventos do Estado. Com foco na seguran\u00e7a p\u00fablica e na fiscaliza\u00e7\u00e3o extramuros, a institui\u00e7\u00e3o estar\u00e1 presente na ExpoCa\u00e7ador 2026, que acontece entre os dias 20 e 23 de mar\u00e7o, no Parque das Arauc\u00e1rias, em Ca\u00e7ador.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ao todo, dez policiais penais estar\u00e3o mobilizados durante o evento, atuando de forma estrat\u00e9gica por meio de equipes especializadas. A opera\u00e7\u00e3o contar\u00e1 com a participa\u00e7\u00e3o da Unidade de Monitoramento Eletr\u00f4nico, do N\u00facleo de Busca e Recaptura da Pol\u00edcia Penal (RECAP) e do N\u00facleo de Opera\u00e7\u00f5es T\u00e1ticas da Regional Serrana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A Unidade de Monitoramento Eletr\u00f4nico ser\u00e1 respons\u00e1vel por acompanhar, em tempo real, pessoas que utilizam tornozeleira eletr\u00f4nica. Atualmente, Santa Catarina possui 4.618 monitorados, muitos deles com restri\u00e7\u00f5es judiciais, como a proibi\u00e7\u00e3o de frequentar festas e eventos. Com o uso da tecnologia, ser\u00e1 poss\u00edvel identificar eventuais descumprimentos e acionar rapidamente as equipes em campo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">O N\u00facleo de Busca e Recaptura (RECAP) atuar\u00e1 diretamente na abordagem e, quando necess\u00e1rio, na recaptura de monitorados que estejam em desacordo com as medidas impostas pela Justi\u00e7a ou em situa\u00e7\u00e3o suspeita. J\u00e1 o N\u00facleo de Opera\u00e7\u00f5es T\u00e1ticas dar\u00e1 suporte \u00e0s a\u00e7\u00f5es, garantindo pronta resposta e refor\u00e7o operacional durante toda a programa\u00e7\u00e3o da feira.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A secret\u00e1ria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Danielle Amorim, destacou o papel da institui\u00e7\u00e3o no acompanhamento de pessoas monitoradas. \u201cEsse trabalho permite uma fiscaliza\u00e7\u00e3o mais efetiva do cumprimento das medidas judiciais, garantindo que restri\u00e7\u00f5es sejam respeitadas mesmo em ambientes com grande circula\u00e7\u00e3o de pessoas\u201d, afirmou.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A ExpoCa\u00e7ador 2026 \u00e9 promovida pela Prefeitura de Ca\u00e7ador e integra as comemora\u00e7\u00f5es dos 92 anos do munic\u00edpio. O evento re\u00fane setores como agroneg\u00f3cio, ind\u00fastria, com\u00e9rcio, servi\u00e7os e conhecimento, al\u00e9m de oferecer uma ampla programa\u00e7\u00e3o com exposi\u00e7\u00f5es, oportunidades de neg\u00f3cios, atra\u00e7\u00f5es culturais, shows nacionais e o tradicional rodeio country.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Com a presen\u00e7a na feira, a Pol\u00edcia Penal reafirma seu papel estrat\u00e9gico na seguran\u00e7a p\u00fablica, atuando de forma preventiva, integrada e cada vez mais pr\u00f3xima da comunidade.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A atua\u00e7\u00e3o cada vez mais moderna, tecnol\u00f3gica e integrada da Pol\u00edcia Penal de Santa Catarina tamb\u00e9m se reflete na presen\u00e7a em grandes eventos do Estado. Com foco na seguran\u00e7a p\u00fablica e na fiscaliza\u00e7\u00e3o extramuros, a institui\u00e7\u00e3o estar\u00e1 presente na ExpoCa\u00e7ador 2026, que acontece entre os dias 20 e 23 de mar\u00e7o, no Parque das Arauc\u00e1rias, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24428,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:00:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24420"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=24420"}],"version-history":[{"count":1,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24420\/revisions"}],"predecessor-version":[{"id":24421,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24420\/revisions\/24421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/24428"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=24420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=24420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=24420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}