{"id":2534,"date":"2009-07-23T18:04:28","date_gmt":"2009-07-23T18:04:28","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2009\/07\/23\/ressocializacao-casa-de-semiliberdade-realiza-1-colonia-de-ferias-para-adolescentes\/"},"modified":"2009-07-23T18:04:28","modified_gmt":"2009-07-23T18:04:28","slug":"ressocializacao-casa-de-semiliberdade-realiza-1-colonia-de-ferias-para-adolescentes","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/ressocializacao-casa-de-semiliberdade-realiza-1-colonia-de-ferias-para-adolescentes\/","title":{"rendered":"Ressocializa\u00e7\u00e3o: Casa de Semiliberdade realiza 1\u00aa Col\u00f4nia de F\u00e9rias para adolescentes"},"content":{"rendered":"<table border=\"0\">\n<tbody>\n<tr>\n<td rowspan=\"2\" align=\"left\" valign=\"top\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">Encerrou no dia 28 de janeiro \u00faltimo, a 1\u00aa Col\u00f4nia de F\u00e9rias para adolescentes em conflito com a lei, realizada pela Casa de Semiliberdade do munic\u00edpio de Bigua\u00e7u. Sob a coordena\u00e7\u00e3o do Centro de Reabilita\u00e7\u00e3o Especializado em Depend\u00eancia Qu\u00edmica (CREDC), a gincana come\u00e7ou na ter\u00e7a 20 e reuniu 18 adolescentes entre 14 e 18 anos, dos programas de semiliberdade de Blumenau, Itaja\u00ed e Bigua\u00e7u.<br \/> <\/span><\/td>\n<td valign=\"top\"><\/td>\n<\/tr>\n<tr>\n<td align=\"center\">&nbsp;Adolesecente que cumpre medida recebe instru\u00e7\u00f5es de montaria da PM<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">Idealizados pelos coordenadores&nbsp; Matheus Mello e Alexandre Lima, o programa teve o apoio da Pol\u00edcia Militar na pessoa do major Eriberto Peres, do Corpo de Bombeiros, soldado Roberto Figueiredo, al\u00e9m do acompanhamento de psic\u00f3logos, educadores e demais coordenadores. O objetivo do projeto foi a ressocializa\u00e7\u00e3o dos menores. <\/span><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\"><\/span><span style=\"font-size: 10pt; font-family: georgia,palatino;\">Durante a programa\u00e7\u00e3o, os internos participaram de palestras sobre doen\u00e7as sexualmente transmiss\u00edveis com o Grupo de Apoio \u00e0 Preven\u00e7\u00e3o da Aids (GAPA),&nbsp; preven\u00e7\u00e3o \u00e0s drogas pelo Programa Educacional de Resist\u00eancia \u00e0s Drogas e \u00e0 Viol\u00eancia (PROERD) da Pol\u00edcia Militar. Tamb\u00e9m tiveram instru\u00e7\u00f5es de primeiros socorros, combate a inc\u00eandios, al\u00e9m de atividades desportivas, din\u00e2mica de grupo, descida de rapel, tirolesa (cabo a\u00e9reo), entre outras. <\/span><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">Segundo o coordenador Alexandre Lima, em todo o tempo os participantes da &#8220;gincana&#8221; estavam sendo avaliados pelos educadores, quanto ao comportamento e a interatividade em grupo. &#8220;N\u00f3s n\u00e3o descart\u00e1vamos que houvesse alguma discuss\u00e3o durante as etapas, mas estamos satisfeitos porque tudo ocorreu melhor do que esper\u00e1vamos&#8221;, relatou Lima. <\/span><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">O diretor do Departamento de Justi\u00e7a e Cidadania, Itamar Bressan Bonelli, que esteve presente no encerramento, se disse muito satisfeito pelos resultados obtidos nesta primeira edi\u00e7\u00e3o, e n\u00e3o descarta para o pr\u00f3ximo ano a realiza\u00e7\u00e3o de uma olimp\u00edada envolvendo as unidades de todo o Estado. Ao final os educadores e internos foram homenageados com entrega de medalhas. &nbsp; <\/span><\/div>\n<div align=\"justify\"> <span style=\"font-size: 10pt; font-family: georgia,palatino;\">Assessoria de Comunica\u00e7\u00e3o <br \/> Departamento de Justi\u00e7a e Cidadania (DJUC)<br \/> Diretor Itamar Bressan Bonelli<br \/> Assessor: Emerson Machado DRT 3275SC<br \/> Fone: 21072994 <\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Encerrou no dia 28 de janeiro \u00faltimo, a 1\u00aa Col\u00f4nia de F\u00e9rias para adolescentes em conflito com a lei, realizada pela Casa de Semiliberdade do munic\u00edpio de Bigua\u00e7u. Sob a coordena\u00e7\u00e3o do Centro de Reabilita\u00e7\u00e3o Especializado em Depend\u00eancia Qu\u00edmica (CREDC), a gincana come\u00e7ou na ter\u00e7a 20 e reuniu 18 adolescentes entre 14 e 18 anos, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:04:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2534"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2534"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/8"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}