{"id":2549,"date":"2009-07-23T18:06:29","date_gmt":"2009-07-23T18:06:29","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2009\/07\/23\/djuc-recebe-representantes-do-ministerio-publico\/"},"modified":"2009-07-23T18:06:29","modified_gmt":"2009-07-23T18:06:29","slug":"djuc-recebe-representantes-do-ministerio-publico","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/djuc-recebe-representantes-do-ministerio-publico\/","title":{"rendered":"DJUC recebe representantes do Minist\u00e9rio P\u00fablico"},"content":{"rendered":"<table border=\"0\">\n<tbody>\n<tr>\n<td rowspan=\"2\" align=\"left\" valign=\"top\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">O diretor do Departamento de Justi\u00e7a e Cidadania (DJUC), Itamar Bressan Boneli, recebeu na ter\u00e7a-feira (14), representantes do Minist\u00e9rio P\u00fablico. O objetivo do encontro foi a avalia\u00e7\u00e3o das fun\u00e7\u00f5es e atribui\u00e7\u00f5es inerentes as atividade desenvolvidas pelas unidades de internamento do adolescente em conflito com a lei, no Estado.<\/span><\/td>\n<td valign=\"top\"><\/td>\n<\/tr>\n<tr align=\"center\">\n<td align=\"center\">O encontro, contou tamb\u00e9m, com a participa\u00e7\u00e3o de gerentes e assessores de gabinete.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--><\/p>\n<div align=\"justify\"> <span style=\"font-size: 10pt; font-family: georgia,palatino;\">As promotoras de justi\u00e7a, Priscila Albino, respons\u00e1vel pela coordena\u00e7\u00e3o do Centro de Apoio da Inf\u00e2ncia e Juventude e Vanessa Cavallazzi Gomes da 9\u00aa promotoria de justi\u00e7a, demonstraram, durante conversa, a necessidade de uma parceria mais afinada entre os dois poderes, pela busca de estrat\u00e9gias preventivas no setor. &#8220;A preven\u00e7\u00e3o deve acontecer a partir da fam\u00edlia, onde o problema inicia&#8221;, sugeriu Priscila. <\/span><\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">Entre as propostas das agentes, Vanessa destacou a cria\u00e7\u00e3o de resid\u00eancias terap\u00eauticas infanto-juvenil para menores v\u00edtimas de viol\u00eancia dom\u00e9stica, o melhoramento no processo de acompanhamento do interno pela justi\u00e7a, e a implanta\u00e7\u00e3o de um n\u00facleo de capacita\u00e7\u00e3o para monitores. &#8220;Temos como inten\u00e7\u00e3o somar esfor\u00e7os com o governo e a fam\u00edlia pelo aprimoramento e efic\u00e1cia deste trabalho&#8221;, completou Priscila. <\/span><\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">Al\u00e9m de documentos e relat\u00f3rios, a equipe t\u00e9cnica do DJUC apresentou o projeto de implanta\u00e7\u00e3o e implementa\u00e7\u00e3o do Sistema s\u00f3cio-educativo catarinense: Sipia II\/ InfoInfra*, que est\u00e1 em processo de instala\u00e7\u00e3o. De acordo com o diretor Itamar, este sistema de informa\u00e7\u00e3o permitir\u00e1 que o adolescente seja mais bem acompanhado, tanto pela unidade que executa a medida, quanto pela pr\u00f3pria justi\u00e7a. &#8220;Quando ativado, este mecanismo tornar\u00e1 as informa\u00e7\u00f5es muito mais r\u00e1pidas e seguras para todos n\u00f3s&#8221;, noticiou Itamar. <\/span><\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">Uma pr\u00f3xima reuni\u00e3o acontecer\u00e1 no in\u00edcio de agosto na sede da promotoria, onde dar\u00e3o continuidade as propostas e discuss\u00f5es. <\/span><\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: georgia,palatino;\">* Sipia: Sistema de Informa\u00e7\u00e3o para a Inf\u00e2ncia e Adolesc\u00eancia.<br \/> InfoInfra: Sistema que monitora o fluxo de atendimento ao adolescente em conflito com a lei. <\/span><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<div align=\"justify\"><span style=\"font-size: 10pt; font-family: Georgia;\">Assessoria de Comunica\u00e7\u00e3o<br \/> Departamento de Justi\u00e7a e Cidadania (DJUC)<br \/> Diretor Itamar Bressan Bonelli<br \/> Assessor: Emerson Machado DRT 3275SC<br \/> Fone: 21072994<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>O diretor do Departamento de Justi\u00e7a e Cidadania (DJUC), Itamar Bressan Boneli, recebeu na ter\u00e7a-feira (14), representantes do Minist\u00e9rio P\u00fablico. O objetivo do encontro foi a avalia\u00e7\u00e3o das fun\u00e7\u00f5es e atribui\u00e7\u00f5es inerentes as atividade desenvolvidas pelas unidades de internamento do adolescente em conflito com a lei, no Estado. O encontro, contou tamb\u00e9m, com a participa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":12,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:56:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2549"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2549"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}