{"id":2661,"date":"2018-03-20T14:36:16","date_gmt":"2018-03-20T14:36:16","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2018\/03\/20\/forum-de-dirigentes-do-sistema-socioeducativo-foi-aberto-nesta-segunda-feira-em-florianopolis\/"},"modified":"2018-03-20T14:36:16","modified_gmt":"2018-03-20T14:36:16","slug":"forum-de-dirigentes-do-sistema-socioeducativo-foi-aberto-nesta-segunda-feira-em-florianopolis","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/forum-de-dirigentes-do-sistema-socioeducativo-foi-aberto-nesta-segunda-feira-em-florianopolis\/","title":{"rendered":"F\u00f3rum de dirigentes do Sistema Socioeducativo foi aberto nesta segunda-feira em Florian\u00f3polis"},"content":{"rendered":"<p style=\"text-align: justify;\">Com o objetivo de promover a articula\u00e7\u00e3o entre os dirigentes e integrar pr\u00e1ticas de gest\u00e3o, foi aberto nesta segunda-feira, 19, em Florian\u00f3polis, o F\u00f3rum Nacional de Dirigentes Governamentais de Entidades Executoras da Pol\u00edtica de Promo\u00e7\u00e3o e Defesa dos Direitos da Crian\u00e7a e do Adolescente, Fonacriad.<\/p>\n<p style=\"text-align: justify;\">\u201cA socioeduca\u00e7\u00e3o precisa ser melhor entendida como pol\u00edtica p\u00fablica, e o objetivo deste F\u00f3rum \u00e9 articular todas as experi\u00eancias do Brasil voltadas para o adolescente em conflito com a lei de acordo com o que \u00e9 preconizado pelo Sinase, o Sistema Nacional Socioeducativo\u201d, declarou o Secret\u00e1rio de Estado da Justi\u00e7a e Cidadania (SJC), Leandro Lima, na solenidade de abertura do evento realizada na sede do Minist\u00e9rio P\u00fablico Estadual.<\/p>\n<p style=\"text-align: justify;\">A Secret\u00e1ria Nacional dos Direitos da Crian\u00e7a e do Adolescente, do Minist\u00e9rio dos Direitos Humanos (MDH), Berenice Giannella, e o coordenador nacional do Sistema Nacional de Atendimento Socioeducativo (Sinase), Ricardo Peres da Costa tamb\u00e9m participaram da abertura do evento.<\/p>\n<p style=\"text-align: justify;\">De acordo com Peres, o Brasil possui atualmente 27 mil adolescentes cumprindo medida de interna\u00e7\u00e3o e de interna\u00e7\u00e3o provis\u00f3ria e de semiliberdade, s\u00e3o as chamadas medidas de priva\u00e7\u00e3o de restri\u00e7\u00e3o de liberdade; e em torno de 120 mil cumprindo liberdade assistida e presta\u00e7\u00e3o de servi\u00e7o a comunidade, onde permanecem com os familiares. \u201c\u00c9 um n\u00famero que cresce, no entanto estamos trabalhando para melhor atender esta popula\u00e7\u00e3o e oferecer uma condi\u00e7\u00e3o diferente que ajude este adolescente a refletir e encontrar um novo caminho\u201d, destaca o coordenador.<\/p>\n<p style=\"text-align: justify;\">O Diretor do Departamento de Administra\u00e7\u00e3o Socioeducativo (Dease), Zeno Tressoldi, a presidente do Fonacriad, Elis\u00e2ngela Cardoso, e demais autoridades, tamb\u00e9m participaram da abertura do evento que encerra na quarta-feira na Capital.<\/p>\n<p>1\u00aa Reuni\u00e3o T\u00e9cnica do FONACRIAD \u2013 2018<\/p>\n<p>PROGRAMA\u00c7\u00c3O <br \/>Data: 19, 20 e 21 de mar\u00e7o de 2018. <br \/>Local: Audit\u00f3rio do MPSC, Rua Bocai\u00fava, 1750, Casa do Bar\u00e3o, Centro, Florian\u00f3polis. <\/p>\n<p>Dia 20\/03\/18 \u2013 ter\u00e7a-feira: <br \/>(Programa\u00e7\u00e3o Interna \u2013 gestores estaduais) <br \/>8h30min \u2013 Relato do Atendimento Socioeducativo nos Estados da Federa\u00e7\u00e3o; <br \/>10h \u2013 intervalo; <br \/>10h20min \u2013 Secretaria Nacional dos Direitos da Crian\u00e7a e do Adolescente e Coordena\u00e7\u00e3o Nacional do Sinase: a) Status dos Grupos de Trabalho: Normativas de Seguran\u00e7a; b) Convalida\u00e7\u00e3o da 2\u00aa. Oficina referente \u00e0 constru\u00e7\u00e3o dos Par\u00e2metros Nacionais para a Medida Socioeducativa de Semiliberdade; c) Pesquisa da SENAD\/USP; d) Socializa\u00e7\u00e3o dos levantamentos 2015 a 2016; e) Demais informes; <br \/>11h20min \u2013 Interface da Socioeduca\u00e7\u00e3o e FONACRIAD com os Colegiados e instancias Nacionais: CONANDA, CNJ, FONSEAS e MDS; <br \/>12h \u2013 Almo\u00e7o; <br \/>13h30min \u2013 A Gest\u00e3o Administrativa e Financeira a Servi\u00e7o da Socioeduca\u00e7\u00e3o: relato de experi\u00eancia dos estados do Rio Grande do Sul, Esp\u00edrito Santo e Par\u00e1. <br \/>16h \u2013 Intervalo; <br \/>16h20min \u2013 Debate e intera\u00e7\u00e3o com a plen\u00e1ria, a partir dos diferentes contextos Administrativos e Financeiros vividos pelos Estados; <br \/>19h \u2013 Jantar e conviv\u00eancia. <\/p>\n<p>Dia 21\/03\/18 \u2013 quarta-feira: <br \/>8h30min \u2013 Constru\u00e7\u00e3o da Agenda Estrat\u00e9gica do FONACRIAD para 2018\/2019. <br \/>9h30 \u2013 Informes Gerais <br \/>9h50 &#8211; Defini\u00e7\u00e3o de pauta para a 2\u00aa reuni\u00e3o tem\u00e1tica do FONACRIAD, no ano de 2018; <br \/>10h10 \u2013 Intervalo; <br \/>10h30min \u2013 Case de parceria entre Sistema Socioeducativo e Judici\u00e1rio em S\u00e3o Miguel do Oeste. Dra. Larissa Takashima \u2013 Minist\u00e9rio P\u00fablico de SC \u2013 e Dr. J\u00falio Ant\u00f4nio Bagetti, Advogado da Prefeitura de S\u00e3o Miguel do Oeste. <br \/>12h \u2013 Almo\u00e7o; <br \/>13h30min \u2013 Avalia\u00e7\u00e3o do encontro; <br \/>14h \u2013 Encerramento.<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de promover a articula\u00e7\u00e3o entre os dirigentes e integrar pr\u00e1ticas de gest\u00e3o, foi aberto nesta segunda-feira, 19, em Florian\u00f3polis, o F\u00f3rum Nacional de Dirigentes Governamentais de Entidades Executoras da Pol\u00edtica de Promo\u00e7\u00e3o e Defesa dos Direitos da Crian\u00e7a e do Adolescente, Fonacriad. \u201cA socioeduca\u00e7\u00e3o precisa ser melhor entendida como pol\u00edtica p\u00fablica, e [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:10:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2661"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2661"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}