{"id":2666,"date":"2019-01-10T21:04:11","date_gmt":"2019-01-10T21:04:11","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2019\/01\/10\/dease-reune-gestores-para-debater-acoes-nas-unidades-socioeducativas\/"},"modified":"2019-01-10T21:04:11","modified_gmt":"2019-01-10T21:04:11","slug":"dease-reune-gestores-para-debater-acoes-nas-unidades-socioeducativas","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/dease-reune-gestores-para-debater-acoes-nas-unidades-socioeducativas\/","title":{"rendered":"DEASE re\u00fane gestores para debater a\u00e7\u00f5es nas unidades socioeducativas"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dando prosseguimento aos encontros com todos os gestores que atuam na Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa, o titular da pasta, Leandro Lima, participou nesta quinta-feira (11) de uma reuni\u00e3o com os gestores dos CASE, CASEP e Casas de Semiliberdade administradas pelo DEASE. \u201cNosso desafio \u00e9 ter o melhor sistema socioeducativo do pa\u00eds e a contribui\u00e7\u00e3o dos servidores na implementa\u00e7\u00e3o de boas pr\u00e1ticas de gest\u00e3o \u00e9 fundamental para o aprimoramento do sistema socioeducativo.&nbsp;O Diretor do Dease, Zeno Tressoldi, destacou que o diagn\u00f3stico elaborado pelos gestores permite o estabelecimento de prioridades, troca de experi\u00eancias com a consequente melhora dos resultados.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Dando prosseguimento aos encontros com todos os gestores que atuam na Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa, o titular da pasta, Leandro Lima, participou nesta quinta-feira (11) de uma reuni\u00e3o com os gestores dos CASE, CASEP e Casas de Semiliberdade administradas pelo DEASE. \u201cNosso desafio \u00e9 ter o melhor sistema socioeducativo do pa\u00eds e a [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:10:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2666"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2666"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/211"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}