{"id":2681,"date":"2019-06-07T17:15:19","date_gmt":"2019-06-07T17:15:19","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2019\/06\/07\/casep-de-sao-jose-do-cedro-adere-a-formacao-continuada\/"},"modified":"2019-06-07T17:15:19","modified_gmt":"2019-06-07T17:15:19","slug":"casep-de-sao-jose-do-cedro-adere-a-formacao-continuada","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/casep-de-sao-jose-do-cedro-adere-a-formacao-continuada\/","title":{"rendered":"CASEP de S\u00e3o Jos\u00e9 do Cedro Adere \u00e0 Forma\u00e7\u00e3o Continuada"},"content":{"rendered":"<p style=\"margin: 1pt 0cm 1pt -1cm; text-align: justify; text-indent: 2cm;\">O CASEP de S\u00e3o Jos\u00e9 do Cedro, administrado pela ONG, Associa\u00e7\u00e3o Bet\u00e2nia, iniciou em fevereiro do corrente ano um projeto de forma\u00e7\u00e3o continuada com seus servidores o qual tem como objetivo prepar\u00e1-los para eventuais situa\u00e7\u00f5es de risco que possam comprometer a seguran\u00e7a da unidade socioeducativa.<\/p>\n<p style=\"margin: 1pt 0cm 1pt -1cm; text-align: justify; text-indent: 2cm;\">Conforme esclarece o coordenador, Sr. Roberto Eurico Ferraz, a qualifica\u00e7\u00e3o serve tamb\u00e9m, para garantir \u00e0 seguran\u00e7a de todos os profissionais que trabalham na unidade, equipe t\u00e9cnica, professores e demais colaboradores que de uma forma ou de outra, contribuem para o processo de ressocializa\u00e7\u00e3o.<\/p>\n<p style=\"margin: 1pt 0cm 1pt -1cm; text-align: justify; text-indent: 2cm;\">Ainda, segundo o coordenador, a unidade de S\u00e3o Jos\u00e9 do Cedro est\u00e1 a seis (6) anos sem ocorr\u00eancias de fugas\/evas\u00f5es, motim ou rebeli\u00f5es, em virtude de treinamentos focados na capacita\u00e7\u00e3o dos profissionais que atuam na unidade, onde tem duas prioridades <strong>RESSOCIALIZA\u00c7\u00c3O e SEGURAN\u00c7A<\/strong>, acreditando que somente desta forma poder\u00e3o garantir que os adolescentes retornem ao conv\u00edvio familiar socializados.<\/p>","protected":false},"excerpt":{"rendered":"<p>O CASEP de S\u00e3o Jos\u00e9 do Cedro, administrado pela ONG, Associa\u00e7\u00e3o Bet\u00e2nia, iniciou em fevereiro do corrente ano um projeto de forma\u00e7\u00e3o continuada com seus servidores o qual tem como objetivo prepar\u00e1-los para eventuais situa\u00e7\u00f5es de risco que possam comprometer a seguran\u00e7a da unidade socioeducativa. Conforme esclarece o coordenador, Sr. Roberto Eurico Ferraz, a qualifica\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:57:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2681"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2681"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}