{"id":2704,"date":"2019-07-29T17:37:52","date_gmt":"2019-07-29T17:37:52","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2019\/07\/29\/casep-de-xanxere-realiza-sonho-e-monta-uma-marcenaria-para-atividades-com-adolescentes\/"},"modified":"2019-07-29T17:37:52","modified_gmt":"2019-07-29T17:37:52","slug":"casep-de-xanxere-realiza-sonho-e-monta-uma-marcenaria-para-atividades-com-adolescentes","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/casep-de-xanxere-realiza-sonho-e-monta-uma-marcenaria-para-atividades-com-adolescentes\/","title":{"rendered":"CASEP de Xanxer\u00ea realiza sonho e monta uma marcenaria para atividades com adolescentes"},"content":{"rendered":"<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; text-align: justify;\">A unidade de Xanxer\u00ea realiza sonho e monta uma marcenaria para atividades educativas profissionalizantes com adolescentes, o que \u00e9 mostrado no site Lances Not\u00edcias (<a href=\"http:\/\/www.lancesnoticias.com.br\/\">www.lancesnoticias.com.br<\/a>) divulgado no \u00faltimo dia 26:<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; text-align: justify;\">\u201cO projeto finalmente saiu do papel, depois de meses, e o Centro de Atendimento Socioeducativo Provis\u00f3rio (<em>Casep<\/em>) de&nbsp;<em>Xanxer\u00ea<\/em>&nbsp;iniciou nessa semana o curso de marcenaria.<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; text-align: justify;\">Os adolescentes em conflitos com a Lei est\u00e3o conhecendo as ferramentas e na pr\u00f3xima semana um professor volunt\u00e1rio ir\u00e1 ministrar as aulas te\u00f3ricas e pr\u00e1ticas sobre a profiss\u00e3o.<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; orphans: 2; text-align: justify; widows: 2; word-spacing: 0px;\">Conforme o coordenador Valomir Giraldi, a equipe do Casep conseguiu os equipamentos e tamb\u00e9m a mat\u00e9ria prima para iniciar essa atividade. Um espa\u00e7o tamb\u00e9m foi montado para que os adolescentes possam fabricar as pe\u00e7as e se profissionalizar.<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; text-align: justify;\">Para Valomir, o projeto tamb\u00e9m visa possibilitar aos adolescentes uma poss\u00edvel profiss\u00e3o quando eles retornarem para a sociedade.<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; orphans: 2; text-align: justify; widows: 2; word-spacing: 0px;\">\u2013 Tudo a gente recebeu por doa\u00e7\u00e3o. Conseguimos com o F\u00f3rum, com a comunidade, enfim, essas ferramentas e realizamos o sonho de montar a marcenaria.<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; orphans: 2; text-align: justify; widows: 2; word-spacing: 0px;\">Eles ter\u00e3o um professor que vai dar aulas te\u00f3ricas e pr\u00e1ticas. Al\u00e9m de ocupar o tempo aqui dentro o objetivo \u00e9 profissionaliz\u00e1-los para que saiam da unidade com algo a mais. Nesse primeiro momento eles far\u00e3o objetos para levarem para casa, mas a ideia tamb\u00e9m \u00e9 que se monte moveis para serem comercializados e com o dinheiro adquirir mat\u00e9ria prima novamente \u2013 explica o coordenador.<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; orphans: 2; text-align: justify; widows: 2; word-spacing: 0px;\">O Casep de Xanxer\u00ea conta com seis adolescentes internos, sendo de Xanxer\u00ea, Faxinal dos Guedes, Capinzal e Xaxim. Al\u00e9m desse curso de marcenaria, eles tamb\u00e9m j\u00e1 realizaram curso de mec\u00e2nica automotiva e ainda participam de aulas de capoeira, viol\u00e3o somando ao projeto de leituras.<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; background: #f7f7f7; orphans: 2; text-align: justify; widows: 2; word-spacing: 0px;\">De acordo com Valomir, a comunidade est\u00e1 convidada a conhecer a unidade e as atividades realizadas pelos adolescentes atrav\u00e9s de agendamentos a serem feitos pelo telefone 3433-7659\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>A unidade de Xanxer\u00ea realiza sonho e monta uma marcenaria para atividades educativas profissionalizantes com adolescentes, o que \u00e9 mostrado no site Lances Not\u00edcias (www.lancesnoticias.com.br) divulgado no \u00faltimo dia 26: \u201cO projeto finalmente saiu do papel, depois de meses, e o Centro de Atendimento Socioeducativo Provis\u00f3rio (Casep) de&nbsp;Xanxer\u00ea&nbsp;iniciou nessa semana o curso de marcenaria. Os [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:59:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2704"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2704"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}