{"id":2719,"date":"2019-09-03T14:22:54","date_gmt":"2019-09-03T14:22:54","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2019\/09\/03\/agosto-lilas-casep-de-curitibanos\/"},"modified":"2019-09-03T14:22:54","modified_gmt":"2019-09-03T14:22:54","slug":"agosto-lilas-casep-de-curitibanos","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/agosto-lilas-casep-de-curitibanos\/","title":{"rendered":"Agosto Lil\u00e1s &#8211; CASEP de Curitibanos"},"content":{"rendered":"<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; text-align: justify; line-height: normal;\">O Projeto de conscientiza\u00e7\u00e3o a n\u00e3o viol\u00eancia contra a mulher celebrado no m\u00eas de agosto em todo o Estado de Santa Catarina, teve reflexo, tamb\u00e9m, na unidade socioeducativa de Curitibanos em eventos realizados durante todo o m\u00eas.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-align: justify;\">Os socioeducandos, por meio do teatro e da m\u00fasica, tiveram a oportunidade de representar membros da fam\u00edlia, sentindo na pele a viol\u00eancia sofrida por v\u00e1rias mulheres v\u00edtimas da viol\u00eancia. Foram adaptados textos dando \u00eanfase ao uso exagerado de bebidas alco\u00f3licas e outras drogas.<\/span><\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; text-align: justify; line-height: normal;\">Assim, ao participarem de oficinas teatrais, representando membros da fam\u00edlia que vivenciam situa\u00e7\u00f5es de viol\u00eancia, a unidade, junto com a pedagoga M\u00e1rcia Aparecida Ribeiro Lemos e equipe, acaba proporcionando a eles um momento de conscientiza\u00e7\u00e3o, fazendo com que reflitam sobre esses comportamentos.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Projeto de conscientiza\u00e7\u00e3o a n\u00e3o viol\u00eancia contra a mulher celebrado no m\u00eas de agosto em todo o Estado de Santa Catarina, teve reflexo, tamb\u00e9m, na unidade socioeducativa de Curitibanos em eventos realizados durante todo o m\u00eas. Os socioeducandos, por meio do teatro e da m\u00fasica, tiveram a oportunidade de representar membros da fam\u00edlia, sentindo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:57:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2719"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2719"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}