{"id":2744,"date":"2019-11-04T16:58:07","date_gmt":"2019-11-04T16:58:07","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2019\/11\/04\/historias-da-vida-real\/"},"modified":"2019-11-04T16:58:07","modified_gmt":"2019-11-04T16:58:07","slug":"historias-da-vida-real","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/historias-da-vida-real\/","title":{"rendered":"\u201cHist\u00f3rias da vida real\u201d"},"content":{"rendered":"<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; text-align: justify; text-indent: 35.45pt; line-height: normal;\">&nbsp;<\/p>\n<p style=\"margin-top: 1pt; margin-right: 0cm; margin-bottom: 1pt; text-align: justify; line-height: normal;\">&nbsp; &nbsp; &nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Durante o m\u00eas de outubro o CASEP de Ca\u00e7ador promoveu oficinas semanais com o tema \u201cHIST\u00d3RIAS DA VIDA REAL\u201d objetivando conscientizar os adolescentes sobre os seguintes temas: o uso de drogas na adolesc\u00eancia e a automutila\u00e7\u00e3o, onde aconteceram debates e tamb\u00e9m v\u00eddeos motivacionais com hist\u00f3rias reais provando que \u00e9 poss\u00edvel sim mudar e transformar sua vida se voc\u00ea acreditar que pode.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>&nbsp;<\/em><em>&nbsp; &nbsp; &nbsp; O CASEP possui um grupo parceiro que ajuda a realizar esse trabalho, o For\u00e7a Jovem Universal, que tamb\u00e9m acredita na transforma\u00e7\u00e3o dos adolescentes, estando junto na busca de uma vida mais digna.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><em>02\/10: Grupo For\u00e7a Jovem Universal compareceu ao CASEP e passou para os adolescentes o filme \u201cHELP\u201d e em seguida foi realizado um fechamento discutindo sobre o tema do filme a automutila\u00e7\u00e3o;<\/em><\/p>\n<p style=\"text-align: justify;\"><em>10\/10: V\u00eddeos com depoimentos ver\u00eddicos de adolescentes que escolheram a vida do tr\u00e1fico, mas, com o apoio da fam\u00edlia conseguiram se reerguer e transformar suas vidas.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><em>17\/10: Document\u00e1rio real do professor da USP, Roberto da Silva, um homem que passou quase 30 anos preso e que aos poucos pegou gosto pelos estudos e hoje \u00e9 formado e trabalha em uma das melhores universidades do Brasil. Foi feita tamb\u00e9m uma din\u00e2mica em grupo objetivando que os adolescentes enfrentassem seus medos vencendo adversidades psicol\u00f3gicas.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><em>24\/10: Filme sobre o in\u00edcio do uso de drogas na adolesc\u00eancia e debate em grupo sobre influ\u00eancias de \u201camigos\u201d. Ao final da oficina foi passado um v\u00eddeo motivacional sobre n\u00e3o deixar para amanh\u00e3 metas e a\u00e7\u00f5es, mas sim pensar no hoje, acreditando na reconstru\u00e7\u00e3o da pessoa a cada dia.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><em>29\/04: V\u00eddeo motivacional sobre as \u201cviradas imposs\u00edveis em jogos de futebol\u201d provando que devemos lutar sempre para conquistar nossos objetivos e superar nossos medos.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>&nbsp;<\/em><em>&nbsp; &nbsp; &nbsp;O CASEP de Ca\u00e7ador acredita que as oficinas devem proporcionar a reflex\u00e3o do adolescente, objetivando sua transforma\u00e7\u00e3o de vida e constru\u00e7\u00e3o de metas. Procurou-se escolher temas onde envolvesse a realidade de todos, trabalhando a ressocializa\u00e7\u00e3o acreditando que o imposs\u00edvel \u00e9 o poss\u00edvel nunca tentado.&nbsp; &nbsp; &nbsp; &nbsp;<\/em><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Durante o m\u00eas de outubro o CASEP de Ca\u00e7ador promoveu oficinas semanais com o tema \u201cHIST\u00d3RIAS DA VIDA REAL\u201d objetivando conscientizar os adolescentes sobre os seguintes temas: o uso de drogas na adolesc\u00eancia e a automutila\u00e7\u00e3o, onde aconteceram debates e tamb\u00e9m v\u00eddeos motivacionais com hist\u00f3rias reais provando que \u00e9 poss\u00edvel [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:05:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2744"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2744"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}