{"id":2748,"date":"2019-11-08T16:42:44","date_gmt":"2019-11-08T16:42:44","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2019\/11\/08\/implantacao-de-procedimentos-na-semiliberdade-de-criciuma\/"},"modified":"2019-11-08T16:42:44","modified_gmt":"2019-11-08T16:42:44","slug":"implantacao-de-procedimentos-na-semiliberdade-de-criciuma","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/implantacao-de-procedimentos-na-semiliberdade-de-criciuma\/","title":{"rendered":"Implanta\u00e7\u00e3o de procedimentos na Semiliberdade de Crici\u00fama"},"content":{"rendered":"<\/p>\n<p style=\"margin-bottom: 0.0001pt; text-align: justify; text-indent: 35.4pt; line-height: 150%;\">No dia 07 de novembro de 2019, no F\u00f3rum da Comarca de Crici\u00fama, foi realizada reuni\u00e3o de alinhamento de parceria e implanta\u00e7\u00e3o de procedimentos na Unidade de Semiliberdade de Crici\u00fama.<\/p>\n<p style=\"margin-bottom: 0.0001pt; text-align: justify; text-indent: 35.4pt; line-height: 150%;\">O encontro contou com a presen\u00e7a do Juiz da Vara da Inf\u00e2ncia de Crici\u00fama Giancarlo Bremer Nones, do Promotor de Justi\u00e7a Carlos Eduardo Tremel de Faria, da Pol\u00edcia Militar Major Eduardo Moreno Persson e Tenente Gustavo Ramos May, do Gestor da Unidade de Semiliberdade de Crici\u00fama Paulo Eduardo de Matos Adames, da Assessoria Jur\u00eddica Edi Lu\u00edza Napoli Nishioka e da Assessoria de Gabinete Vanessa de Assis Martins.<\/p>\n<p style=\"margin-bottom: 0.0001pt; text-align: justify; text-indent: 35.4pt; line-height: 150%;\">Teve como objetivo discutir o aumento de oferta de atividades laborais e educacionais para os adolescentes e o planejamento estrat\u00e9gico de procedimentos operacionais.<\/p>","protected":false},"excerpt":{"rendered":"<p>No dia 07 de novembro de 2019, no F\u00f3rum da Comarca de Crici\u00fama, foi realizada reuni\u00e3o de alinhamento de parceria e implanta\u00e7\u00e3o de procedimentos na Unidade de Semiliberdade de Crici\u00fama. O encontro contou com a presen\u00e7a do Juiz da Vara da Inf\u00e2ncia de Crici\u00fama Giancarlo Bremer Nones, do Promotor de Justi\u00e7a Carlos Eduardo Tremel de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:06:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2748"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2748"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}