{"id":2774,"date":"2020-05-12T12:36:01","date_gmt":"2020-05-12T12:36:01","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2020\/05\/12\/curso-plataforma-ead-casep-de-rio-do-sul\/"},"modified":"2020-05-12T12:36:01","modified_gmt":"2020-05-12T12:36:01","slug":"curso-plataforma-ead-casep-de-rio-do-sul","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/curso-plataforma-ead-casep-de-rio-do-sul\/","title":{"rendered":"Curso plataforma EAD \u2013 CASEP de Rio do Sul"},"content":{"rendered":"<\/p>\n<p style=\"margin-top: 1pt; text-align: left; text-indent: 0cm;\">Iniciou no m\u00eas de maio, o Curso de Matem\u00e1tica para os socioeducandos do CASEP Rio de Sul; proposta de uma parceria com a Faculdade Senac Rio do Sul e Senac &#8211; SC.<\/p>\n<p style=\"margin-top: 1pt; line-height: normal;\">O Curso acontece em plataforma EAD tendo como aux\u00edlio pedag\u00f3gico a Pedagoga da unidade \u2013 Sra. Sueli Wanzuita -.<\/p>\n<p style=\"margin-top: 1pt; text-align: left; text-indent: 0cm;\">Percebendo, que a maioria dos socioeducandos est\u00e3o a tempo longe do mundo escolar, e muitos deles em defasagem de conhecimentos b\u00e1sicos, entendeu-se que esta ferramenta possibilitar\u00e1 uma evolu\u00e7\u00e3o significativa no processo de aprendizagem dos jovens, permitindo agregar conhecimentos para quando estiverem em sala de aulas, ou mesmo, retornando \u00e0 sociedade.<\/p>\n<p style=\"margin-top: 1pt; text-align: justify; line-height: normal;\">Vamos em frente, &#8220;Juntos Somos Mais Fortes&#8221;<\/p>","protected":false},"excerpt":{"rendered":"<p>Iniciou no m\u00eas de maio, o Curso de Matem\u00e1tica para os socioeducandos do CASEP Rio de Sul; proposta de uma parceria com a Faculdade Senac Rio do Sul e Senac &#8211; SC. O Curso acontece em plataforma EAD tendo como aux\u00edlio pedag\u00f3gico a Pedagoga da unidade \u2013 Sra. Sueli Wanzuita -. Percebendo, que a maioria [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:06:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2774"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2774"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}