{"id":2809,"date":"2020-12-21T20:47:53","date_gmt":"2020-12-21T20:47:53","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2020\/12\/21\/dia-d-unidades-socioeducativas-realizam-mutirao-de-limpeza-e-desinfeccao\/"},"modified":"2020-12-21T20:47:53","modified_gmt":"2020-12-21T20:47:53","slug":"dia-d-unidades-socioeducativas-realizam-mutirao-de-limpeza-e-desinfeccao","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/dia-d-unidades-socioeducativas-realizam-mutirao-de-limpeza-e-desinfeccao\/","title":{"rendered":"&#8220;DIA D\u201d &#8211; UNIDADES SOCIOEDUCATIVAS REALIZAM MUTIR\u00c3O DE LIMPEZA E DESINFEC\u00c7\u00c3O"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 14px; text-align: justify; text-indent: 42.55pt;\">A limpeza e a desinfec\u00e7\u00e3o de superf\u00edcies s\u00e3o elementos que convergem para a sensa\u00e7\u00e3o de bem-estar, seguran\u00e7a e conforto das pessoas que vivem e trabalham em ambientes confinados. Corrobora tamb\u00e9m para o controle das infec\u00e7\u00f5es relacionadas \u00e0 assist\u00eancia \u00e0 sa\u00fade, por garantir um ambiente com superf\u00edcies limpas, com redu\u00e7\u00e3o do n\u00famero de microrganismos e apropriadas para a realiza\u00e7\u00e3o das atividades desenvolvidas nesses servi\u00e7os.<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 42.55pt;\">Visando minimizar a dissemina\u00e7\u00e3o do Novo Coronav\u00edrus nas Unidades Socioeducativas de Santa Catarina, aconteceu de 14 a 18 de dezembro de 2020, o \u201cDia D\u201d de mutir\u00e3o de limpeza e desinfec\u00e7\u00e3o nas Unidades Casa de Semiliberdade de Blumenau, Casep de Blumenau, Casep de Conc\u00f3rdia, Casep de Joinville, Casep de S\u00e3o Jos\u00e9 do Cedro, Casep de Xanxer\u00ea e Case de Crici\u00fama, dentro das recomenda\u00e7\u00f5es estabelecidas no Manual de Desinfec\u00e7\u00e3o da SAP.<\/p>\n<p style=\"text-align: center;\">Casa de Semiliberdade de Blumenau<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-527\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2020\/12\/Fotos_Casep_Blumenau_Dia_D-e57.png\" alt=\"Fotos Casep Blumenau Dia D\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"540\" height=\"235\" \/>Casep de Blumenau<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-full wp-image-528\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2020\/12\/Fotos_Casep_Concordia_Dia_D-d4c.png\" alt=\"Fotos Casep Conc\u00f3rdia Dia D\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"402\" height=\"441\" \/>Casep de Conc\u00f3rdia<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-full wp-image-529\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2020\/12\/Fotos_Casep_Joinville_Dia_D-4ab.png\" alt=\"Fotos Casep Joinville Dia D\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"356\" height=\"455\" \/>Casep de Joinville<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-530\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2020\/12\/Fotos_Casep_SJC_Dia_D-3cf.png\" alt=\"Fotos Casep SJC Dia D\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"489\" height=\"500\" \/>Casep de S\u00e3o Jos\u00e9 do Cedro<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-531\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2020\/12\/Fotos_Casep_Xanxere_Dia_D-d25.png\" alt=\"Fotos Casep Xanxer\u00ea Dia D\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"549\" height=\"423\" \/>Casep de Xanxer\u00ea<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-532\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2020\/12\/Fotos_Case_Criciuma_Dia_D-976.png\" alt=\"Fotos Case Crici\u00fama Dia D\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"422\" height=\"492\" \/>Case de Crici\u00fama<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 42.55pt;\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>A limpeza e a desinfec\u00e7\u00e3o de superf\u00edcies s\u00e3o elementos que convergem para a sensa\u00e7\u00e3o de bem-estar, seguran\u00e7a e conforto das pessoas que vivem e trabalham em ambientes confinados. Corrobora tamb\u00e9m para o controle das infec\u00e7\u00f5es relacionadas \u00e0 assist\u00eancia \u00e0 sa\u00fade, por garantir um ambiente com superf\u00edcies limpas, com redu\u00e7\u00e3o do n\u00famero de microrganismos e apropriadas [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:20:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2809"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2809"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}