{"id":2835,"date":"2021-05-05T21:43:10","date_gmt":"2021-05-05T21:43:10","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/05\/05\/doacao-de-sangue-um-ato-amor\/"},"modified":"2021-05-05T21:43:10","modified_gmt":"2021-05-05T21:43:10","slug":"doacao-de-sangue-um-ato-amor","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/doacao-de-sangue-um-ato-amor\/","title":{"rendered":"\u201cDoa\u00e7\u00e3o de sangue, um ato amor\u201d"},"content":{"rendered":"<\/p>\n<p style=\"font-size: 14px; line-height: normal; background-color: white; background-image: url('initial'); background-repeat: initial; background-attachment: initial; text-align: justify; text-indent: 35.4pt;\">A promo\u00e7\u00e3o da sa\u00fade e engajamento da popula\u00e7\u00e3o s\u00e3o conceitos motivados pela coopera\u00e7\u00e3o dentro da sociedade e tem como objetivo principal somar na vida do pr\u00f3ximo. Ou seja, envolve a\u00e7\u00f5es e rea\u00e7\u00f5es sendo estabelecida quando entramos em contato com o outro, afetando, assim, seu comportamento ou condi\u00e7\u00e3o de forma positiva.&nbsp;<\/p>\n<p style=\"font-size: 14px; line-height: normal; background-color: white; background-image: url('initial'); background-repeat: initial; background-attachment: initial; text-align: justify; text-indent: 35.4pt;\">Buscando despertar sobre a import\u00e2ncia do ato volunt\u00e1rio da doa\u00e7\u00e3o de sangue, o Casep de Xanxer\u00ea desenvolveu e concretizou o projeto \u201cDoa\u00e7\u00e3o de sangue, um ato de amor\u201d. Os colaboradores da Unidade reuniram-se e compareceram no HEMOSC de Chapec\u00f3 para a doa\u00e7\u00e3o, com o objetivo de auxiliar as pessoas que necessitam deste ato, pois uma doa\u00e7\u00e3o de sangue pode salvar v\u00e1rias vidas.<\/p>\n<p style=\"font-size: 14px; line-height: normal; background-color: white; background-image: url('initial'); background-repeat: initial; background-attachment: initial; text-align: justify; text-indent: 35.4pt;\">N\u00e3o h\u00e1 nada no mundo que substitua o sangue humano, por isso sempre que uma pessoa necessita de uma transfus\u00e3o, depende da boa a\u00e7\u00e3o das pessoas que se dispuseram a doar sangue para abastecer os estoques m\u00e9dicos. A doa\u00e7\u00e3o de sangue \u00e9 um ato simples e altru\u00edsta e ao doar o indiv\u00edduo est\u00e1 ajudando quem necessita urgentemente desse item essencial para a sobreviv\u00eancia.&nbsp;&nbsp;<\/p>\n<p style=\"font-size: 14px; line-height: normal; background-color: white; background-image: url('initial'); background-repeat: initial; background-attachment: initial; text-align: justify; text-indent: 35.4pt;\">As a\u00e7\u00f5es de conscientiza\u00e7\u00e3o e movimenta\u00e7\u00e3o para doa\u00e7\u00e3o de sangue podem ser exploradas como uma forma de estimular o pensamento em prol da comunidade, pois incentivar a doa\u00e7\u00e3o de sangue \u00e9 al\u00e9m de motivar o compromisso social, \u00e9 motivar a vida!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-607\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2021\/05\/Doacao_de_sangue_2-f37.jpg\" width=\"400\" height=\"400\" alt=\"Doa\u00e7\u00e3o de sangue 2\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A promo\u00e7\u00e3o da sa\u00fade e engajamento da popula\u00e7\u00e3o s\u00e3o conceitos motivados pela coopera\u00e7\u00e3o dentro da sociedade e tem como objetivo principal somar na vida do pr\u00f3ximo. Ou seja, envolve a\u00e7\u00f5es e rea\u00e7\u00f5es sendo estabelecida quando entramos em contato com o outro, afetando, assim, seu comportamento ou condi\u00e7\u00e3o de forma positiva.&nbsp; Buscando despertar sobre a import\u00e2ncia [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:08:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2835"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2835"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}