{"id":2841,"date":"2021-05-26T20:47:07","date_gmt":"2021-05-26T20:47:07","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/05\/26\/casep-de-sao-miguel-do-oeste-tem-projeto-aprovado-e-recebe-equipamentos-do-conselho-municipal-dos-direitos-da-crianca-e-do-adolescente\/"},"modified":"2021-05-26T20:47:07","modified_gmt":"2021-05-26T20:47:07","slug":"casep-de-sao-miguel-do-oeste-tem-projeto-aprovado-e-recebe-equipamentos-do-conselho-municipal-dos-direitos-da-crianca-e-do-adolescente","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/casep-de-sao-miguel-do-oeste-tem-projeto-aprovado-e-recebe-equipamentos-do-conselho-municipal-dos-direitos-da-crianca-e-do-adolescente\/","title":{"rendered":"Casep de S\u00e3o Miguel do Oeste tem projeto aprovado e recebe equipamentos do Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente"},"content":{"rendered":"<p style=\"font-size: 14px; line-height: normal; text-align: justify; text-indent: 35.4pt;\">No ano de 2021 o Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente &#8211; CMDCA, atrav\u00e9s de recursos do Fundo Municipal da Inf\u00e2ncia e Adolesc\u00eancia &#8211; FIA, lan\u00e7ou edital para inscri\u00e7\u00e3o de projetos sociais, para Organiza\u00e7\u00f5es da Sociedade Civil e da Administra\u00e7\u00e3o P\u00fablica que estejam legalmente registradas e regularizadas junto ao CMDCA. O Casep de S\u00e3o Miguel do Oeste est\u00e1 registrado junto ao Conselho desde o ano de 2018.<\/p>\n<p style=\"font-size: 14px; line-height: normal; text-align: justify; text-indent: 35.4pt;\">Atrav\u00e9s do Gestor da Unidade Sr. Roberto Franceschina e da Equipe T\u00e9cnica, o Casep de S\u00e3o Miguel do Oeste encaminhou um projeto solicitando equipamentos, os quais ser\u00e3o utilizados nas atividades de escolariza\u00e7\u00e3o, oficinas e cursos profissionalizantes, com o objetivo de dar seguimento \u00e0s atividades, estimulando a participa\u00e7\u00e3o de todos os envolvidos.<\/p>\n<p style=\"font-size: 14px; line-height: normal; text-align: justify; text-indent: 35.4pt;\">Salienta-se que a Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa &#8211; SAP e o Dease disponibilizam a estrutura necess\u00e1ria para o funcionamento da Unidade, bem como das oficinas. Com objetivo de incrementar as atividades, o Casep busca parcerias, envolvendo a comunidade e demais redes de apoio no processo de ressocializa\u00e7\u00e3o dos adolescentes em cumprimento de medida socioeducativa privados de liberdade.<\/p>\n<p style=\"font-size: 14px; line-height: normal; text-align: justify; text-indent: 35.4pt;\">O projeto enviado foi aprovado e a Unidade contemplada com 02 TVs 43&#8243; SMART, 01 notebook, 01 mesa de Ping Pong, 01 m\u00e1quina de costura, 01 ro\u00e7adeira a gasolina e 01 esmerilhadeira, totalizando o valor de R$ 12.552,00 (doze mil, quinhentos e cinquenta e dois reais). A parceria do Conselho, representada pelo seu Presidente Sr. Marcio Picolo e a agilidade no processo tornou poss\u00edvel esta concretiza\u00e7\u00e3o.<\/p>\n<p style=\"font-size: 14px; line-height: normal; text-align: justify; text-indent: 35.4pt;\">Gra\u00e7as ao comprometimento de uma equipe e de um Departamento atuante e comprometido, que sempre incentiva novas a\u00e7\u00f5es e contando com parcerias de entidades p\u00fablicas e privadas, conquista-se um processo de ressocializa\u00e7\u00e3o mais efetivo.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>No ano de 2021 o Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente &#8211; CMDCA, atrav\u00e9s de recursos do Fundo Municipal da Inf\u00e2ncia e Adolesc\u00eancia &#8211; FIA, lan\u00e7ou edital para inscri\u00e7\u00e3o de projetos sociais, para Organiza\u00e7\u00f5es da Sociedade Civil e da Administra\u00e7\u00e3o P\u00fablica que estejam legalmente registradas e regularizadas junto ao CMDCA. O Casep [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:11:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2841"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2841"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}