{"id":2843,"date":"2021-05-27T19:22:07","date_gmt":"2021-05-27T19:22:07","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/05\/27\/adolescentes-do-casep-de-blumenau-exploram-o-mundo-da-leitura\/"},"modified":"2021-05-27T19:22:07","modified_gmt":"2021-05-27T19:22:07","slug":"adolescentes-do-casep-de-blumenau-exploram-o-mundo-da-leitura","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/adolescentes-do-casep-de-blumenau-exploram-o-mundo-da-leitura\/","title":{"rendered":"Adolescentes do Casep de Blumenau exploram o mundo da leitura"},"content":{"rendered":"<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">Os adolescentes do Casep de Blumenau participaram de uma atividade diferente. Eles aprenderam como catalogar livros e organizar a biblioteca da Unidade. \u2800\u2800\u2800\u2800\u2800\u2800\u2800\u2800<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">Quatro socioeducandos participaram da a\u00e7\u00e3o e organizaram todo o ambiente. Aprenderam como organizar os exemplares por t\u00edtulos e g\u00eaneros liter\u00e1rios. Com a cataloga\u00e7\u00e3o, a equipe t\u00e9cnica pode fazer a inser\u00e7\u00e3o dos t\u00edtulos no Sise \u2013 Sistema de Informa\u00e7\u00f5es Socioeducativo, possibilitando o registro de leitura dos adolescentes.<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">O objetivo da atividade \u00e9 aproximar os adolescentes da cultura por meio dos livros e conhecer os diversos g\u00eaneros liter\u00e1rios existentes e dispon\u00edveis na Unidade para leitura, oportunizando-os a explorar o mundo da literatura.<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Os adolescentes do Casep de Blumenau participaram de uma atividade diferente. Eles aprenderam como catalogar livros e organizar a biblioteca da Unidade. \u2800\u2800\u2800\u2800\u2800\u2800\u2800\u2800 Quatro socioeducandos participaram da a\u00e7\u00e3o e organizaram todo o ambiente. Aprenderam como organizar os exemplares por t\u00edtulos e g\u00eaneros liter\u00e1rios. Com a cataloga\u00e7\u00e3o, a equipe t\u00e9cnica pode fazer a inser\u00e7\u00e3o dos t\u00edtulos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:14:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2843"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2843"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}