{"id":2844,"date":"2021-05-28T17:05:07","date_gmt":"2021-05-28T17:05:07","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/05\/28\/casa-de-semiliberdade-de-cacador-desenvolve-projeto-alimentacao-saudavel\/"},"modified":"2021-05-28T17:05:07","modified_gmt":"2021-05-28T17:05:07","slug":"casa-de-semiliberdade-de-cacador-desenvolve-projeto-alimentacao-saudavel","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/casa-de-semiliberdade-de-cacador-desenvolve-projeto-alimentacao-saudavel\/","title":{"rendered":"Casa de Semiliberdade de Ca\u00e7ador desenvolve \u201cProjeto Alimenta\u00e7\u00e3o Saud\u00e1vel\u201d"},"content":{"rendered":"<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">Preocupados com a sa\u00fade e alimenta\u00e7\u00e3o dos adolescentes, a Semiliberdade de Ca\u00e7ador construiu uma horta para cultivo de hortali\u00e7as. A constru\u00e7\u00e3o faz parte do &#8220;Projeto Alimenta\u00e7\u00e3o Saud\u00e1vel&#8221;. Foram plantadas mudas de alface, repolho, br\u00f3colis, entre outras hortali\u00e7as.<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">O trabalho \u00e9 fruto de uma parceria da Unidade com empresas da regi\u00e3o: a Casa do Fumo, A Jardineira, Horto Florestal, Floricultura Freisleben e a Cooper HF.<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">Ter uma boa qualidade de vida \u00e9 sin\u00f4nimo de sa\u00fade, principalmente quando se tem h\u00e1bitos alimentares saud\u00e1veis, por isso o &#8220;Projeto Alimenta\u00e7\u00e3o Saud\u00e1vel&#8221; tem como finalidade proporcionar aos adolescentes conhecimentos e valores. Al\u00e9m de garantir a produ\u00e7\u00e3o de alimentos saud\u00e1veis, nutritivos e saborosos, a tarefa di\u00e1ria com os adolescentes traz educa\u00e7\u00e3o, ocupa\u00e7\u00e3o e proporciona momentos de relaxamento, prazer, lazer e pr\u00e1tica de exerc\u00edcios ao ar livre.<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Preocupados com a sa\u00fade e alimenta\u00e7\u00e3o dos adolescentes, a Semiliberdade de Ca\u00e7ador construiu uma horta para cultivo de hortali\u00e7as. A constru\u00e7\u00e3o faz parte do &#8220;Projeto Alimenta\u00e7\u00e3o Saud\u00e1vel&#8221;. Foram plantadas mudas de alface, repolho, br\u00f3colis, entre outras hortali\u00e7as. O trabalho \u00e9 fruto de uma parceria da Unidade com empresas da regi\u00e3o: a Casa do Fumo, A [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:08:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2844"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2844"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}