{"id":2853,"date":"2021-07-12T20:39:50","date_gmt":"2021-07-12T20:39:50","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/07\/12\/centro-socioeducativo-feminino-regional-de-florianopolis-entrega-certificados-do-programa-de-iniciacao-ao-trabalho-pit-centro-de-integracao-empresa-escola-ciee\/"},"modified":"2021-07-12T20:39:50","modified_gmt":"2021-07-12T20:39:50","slug":"centro-socioeducativo-feminino-regional-de-florianopolis-entrega-certificados-do-programa-de-iniciacao-ao-trabalho-pit-centro-de-integracao-empresa-escola-ciee","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/centro-socioeducativo-feminino-regional-de-florianopolis-entrega-certificados-do-programa-de-iniciacao-ao-trabalho-pit-centro-de-integracao-empresa-escola-ciee\/","title":{"rendered":"Centro Socioeducativo Feminino Regional de Florian\u00f3polis entrega Certificados do Programa de Inicia\u00e7\u00e3o ao Trabalho (PIT) &#8211; Centro de Integra\u00e7\u00e3o Empresa-Escola (CIEE)"},"content":{"rendered":"<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">O CIEE \u2013 Centro de Integra\u00e7\u00e3o Empresa-Escola, atrav\u00e9s do PIT \u2013 Programa de Inicia\u00e7\u00e3o ao Trabalho e em parceira com o Dease, oferece aos adolescentes em cumprimento de medida socioeducativa cursos em diversas Unidades do Estado. A oferta de cursos desperta nos adolescentes o interesse pelo mundo do trabalho e a introdu\u00e7\u00e3o \u00e0 capacita\u00e7\u00e3o profissional, o que possibilita, juntamente com a escolariza\u00e7\u00e3o, novas oportunidades para o futuro.<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">O Programa de Inicia\u00e7\u00e3o ao Trabalho \u00e9 um curso com dura\u00e7\u00e3o de 10 dias e carga hor\u00e1ria de 30 horas. Nessa edi\u00e7\u00e3o foram atendidas 09 (nove) adolescentes do Centro Socioeducativo Feminino Regional de Florian\u00f3polis, com encontros realizados tr\u00eas vezes por semana e dura\u00e7\u00e3o de 3 horas.<\/p>\n<p style=\"font-size: 14px; text-align: justify; text-indent: 35.4pt;\">O Curso de Capacita\u00e7\u00e3o Profissional teve in\u00edcio em 18 de junho do corrente ano, cujos objetivos foi proporcionar o acesso a conhecimentos para inser\u00e7\u00e3o no Mundo do Trabalho e apresentados conte\u00fados como entrevista de emprego, curr\u00edculo, planejamento de carreira, intelig\u00eancia emocional, criatividade e inova\u00e7\u00e3o, mundo das profiss\u00f5es.&nbsp;O encerramento aconteceu na data de 09 de julho de 2021, em que ocorreu a formatura e a entrega dos certificados das adolescentes do Centro Socioeducativo Feminino Regional de Florian\u00f3polis, de forma online.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-644\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2021\/07\/CIEE_foto_para_o_site_1-d46.jpg\" alt=\"CIEE foto para o site 1\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"631\" height=\"660\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>O CIEE \u2013 Centro de Integra\u00e7\u00e3o Empresa-Escola, atrav\u00e9s do PIT \u2013 Programa de Inicia\u00e7\u00e3o ao Trabalho e em parceira com o Dease, oferece aos adolescentes em cumprimento de medida socioeducativa cursos em diversas Unidades do Estado. A oferta de cursos desperta nos adolescentes o interesse pelo mundo do trabalho e a introdu\u00e7\u00e3o \u00e0 capacita\u00e7\u00e3o profissional, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:11:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2853"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2853"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}