{"id":2890,"date":"2021-12-21T18:43:54","date_gmt":"2021-12-21T18:43:54","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/12\/21\/dease-realiza-acoes-preventivas-de-revista-estrutural-nas-unidades-socioeducativas\/"},"modified":"2021-12-21T18:43:54","modified_gmt":"2021-12-21T18:43:54","slug":"dease-realiza-acoes-preventivas-de-revista-estrutural-nas-unidades-socioeducativas","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/dease-realiza-acoes-preventivas-de-revista-estrutural-nas-unidades-socioeducativas\/","title":{"rendered":"Dease realiza a\u00e7\u00f5es preventivas de revista estrutural nas Unidades Socioeducativas"},"content":{"rendered":"<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">Nos meses de novembro e dezembro do corrente ano, com apoio de Equipe do Dease &#8211; Departamento de Administra\u00e7\u00e3o Socioeducativa, foram realizadas a\u00e7\u00f5es preventivas de revista estrutural, conforme o planejamento da Opera\u00e7\u00e3o Veraneio promovida pelo Estado, nas seguintes Unidades Socioeducativas:<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">&#8211; Centro de Atendimento Socioeducativo de Itaja\u00ed<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">&#8211; Centro Socioeducativo Regional de Lages<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">&#8211; Casa de Semiliberdade de Lages<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">&#8211; Centro de Atendimento Socioeducativo Provis\u00f3rio de S\u00e3o Miguel do Oeste<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">&#8211; Centro Socioeducativo Regional de Chapec\u00f3<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">&#8211; Centro de Interna\u00e7\u00e3o Feminino de Chapec\u00f3<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">Destaque ainda, para a atua\u00e7\u00e3o dos Gaeses &#8211; Grupos de Apoio e Escolta Socioeducativa e do GOC &#8211; Grupo de Opera\u00e7\u00e3o com C\u00e3es \/Chapec\u00f3.<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">Para o ano de 2022 outras opera\u00e7\u00f5es preventivas j\u00e1 est\u00e3o sendo planejadas e as Unidades Socioeducativas poder\u00e3o contar com o apoio do Dease para qualquer tipo de opera\u00e7\u00e3o de seguran\u00e7a conforme suas necessidades.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-728\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2021\/12\/Foto_revista_estrutural-36a.jpg\" alt=\"Foto revista estrutural\" width=\"489\" height=\"787\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Nos meses de novembro e dezembro do corrente ano, com apoio de Equipe do Dease &#8211; Departamento de Administra\u00e7\u00e3o Socioeducativa, foram realizadas a\u00e7\u00f5es preventivas de revista estrutural, conforme o planejamento da Opera\u00e7\u00e3o Veraneio promovida pelo Estado, nas seguintes Unidades Socioeducativas: &#8211; Centro de Atendimento Socioeducativo de Itaja\u00ed &#8211; Centro Socioeducativo Regional de Lages &#8211; Casa [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:05:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2890"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2890"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}