{"id":2893,"date":"2022-01-06T12:22:49","date_gmt":"2022-01-06T12:22:49","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/01\/06\/dease-realiza-revista-preventiva-planejada-no-case-de-joinville\/"},"modified":"2022-01-06T12:22:49","modified_gmt":"2022-01-06T12:22:49","slug":"dease-realiza-revista-preventiva-planejada-no-case-de-joinville","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/dease-realiza-revista-preventiva-planejada-no-case-de-joinville\/","title":{"rendered":"Dease realiza revista preventiva planejada no Case de Joinville"},"content":{"rendered":"<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">Seguindo o planejamento da Opera\u00e7\u00e3o Veraneio promovida pelo Estado de Santa Catarina, neste dia 05 de janeiro foi dia do Case de Joinville, em parceria com o Dease, realizarem uma opera\u00e7\u00e3o de revista preventiva planejada em suas depend\u00eancias, trazendo mais seguran\u00e7a para suas atividades rotineiras.<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">Destaque ainda, para a atua\u00e7\u00e3o do GOC &#8211; Grupo de Opera\u00e7\u00e3o com C\u00e3es \/ Regional Sul.<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">As Unidades podem contar com a parceria do Departamento de Administra\u00e7\u00e3o Socioeducativa para realizar qualquer tipo de opera\u00e7\u00e3o de seguran\u00e7a conforme suas necessidades.<\/p>\n<p style=\"font-size: 14px; text-align: justify;\">Para este ano, outras opera\u00e7\u00f5es preventivas j\u00e1 est\u00e3o planejadas.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-737\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/01\/Foto_revista_Joinville-fd1.jpg\" alt=\"Foto revista Joinville\" width=\"483\" height=\"955\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Seguindo o planejamento da Opera\u00e7\u00e3o Veraneio promovida pelo Estado de Santa Catarina, neste dia 05 de janeiro foi dia do Case de Joinville, em parceria com o Dease, realizarem uma opera\u00e7\u00e3o de revista preventiva planejada em suas depend\u00eancias, trazendo mais seguran\u00e7a para suas atividades rotineiras. Destaque ainda, para a atua\u00e7\u00e3o do GOC &#8211; Grupo de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:05:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2893"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2893"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}