{"id":523,"date":"2020-12-04T15:49:22","date_gmt":"2020-12-04T15:49:22","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2020\/12\/04\/adolescentes-do-casep-de-sao-miguel-do-oeste-concluem-curso-de-iniciacao-ao-trabalho-digital-2\/"},"modified":"2020-12-04T15:49:22","modified_gmt":"2020-12-04T15:49:22","slug":"adolescentes-do-casep-de-sao-miguel-do-oeste-concluem-curso-de-iniciacao-ao-trabalho-digital-2","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/adolescentes-do-casep-de-sao-miguel-do-oeste-concluem-curso-de-iniciacao-ao-trabalho-digital-2\/","title":{"rendered":"ADOLESCENTES DO CASEP DE S\u00c3O MIGUEL DO OESTE CONCLUEM CURSO DE INICIA\u00c7\u00c3O AO TRABALHO DIGITAL"},"content":{"rendered":"<p style=\"text-align: justify; text-indent: 35.4pt; line-height: 150%;\">Na data de 04\/12\/2020 os adolescentes do CASEP de S\u00e3o Miguel do Oeste receberam o certificado de conclus\u00e3o do curso PROGRAMA DE INICIA\u00c7\u00c3O AO TRABALHO DIGITAL, realizado atrav\u00e9s do PIT \u2013 PROGRAMA DE INICIA\u00c7\u00c3O O TRABALHO do Centro de Integra\u00e7\u00e3o Empresa-Escola de Santa Catarina \u2013 CIEE\/SC.<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; line-height: 150%;\">O curso teve carga hor\u00e1ria de 30 horas, sendo que esta foi a primeira turma a participar dessa nova modalidade de curso 100% on-line, respeitando e cumprindo todas as medidas exigidas para o enfrentamento da COVID-19, como por exemplo, distanciamento m\u00ednimo de 1,5 m entre pessoas, utiliza\u00e7\u00e3o de m\u00e1scara durante todo o per\u00edodo, proibi\u00e7\u00e3o de troca de material como papel ou qualquer outro objeto entre os adolescentes, dentre outras.<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; line-height: 150%;\">Pode se observar que o curso atingiu seus objetivos finais com \u00eaxito, proporcionando aos adolescentes a oportunidade de aprendizado, troca de experi\u00eancias e intera\u00e7\u00e3o e capacitando os mesmos para o mercado de trabalho.<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; line-height: 150%;\">A Equipe do CASEP de S\u00e3o Miguel do Oeste agradece a todos os envolvidos, que se empenharam para a realiza\u00e7\u00e3o de mais esse curso, em especial ao DEASE que firmou a parceria entre Unidade e CIEE. Considerando todas as dificuldades do atual cen\u00e1rio pand\u00eamico que estamos passando, houve a necessidade de se readequar e buscar alternativas para tornar o processo de ressocializa\u00e7\u00e3o cada vez mais eficiente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Na data de 04\/12\/2020 os adolescentes do CASEP de S\u00e3o Miguel do Oeste receberam o certificado de conclus\u00e3o do curso PROGRAMA DE INICIA\u00c7\u00c3O AO TRABALHO DIGITAL, realizado atrav\u00e9s do PIT \u2013 PROGRAMA DE INICIA\u00c7\u00c3O O TRABALHO do Centro de Integra\u00e7\u00e3o Empresa-Escola de Santa Catarina \u2013 CIEE\/SC. O curso teve carga hor\u00e1ria de 30 horas, sendo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:19:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/523"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=523"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/522"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}