{"id":817,"date":"2022-04-13T17:38:57","date_gmt":"2022-04-13T17:38:57","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/04\/13\/unidades-do-dease-desenvolvem-atividades-alusivas-a-pascoa\/"},"modified":"2022-04-13T17:38:57","modified_gmt":"2022-04-13T17:38:57","slug":"unidades-do-dease-desenvolvem-atividades-alusivas-a-pascoa","status":"publish","type":"post","link":"https:\/\/www.sejuri.sc.gov.br\/en\/unidades-do-dease-desenvolvem-atividades-alusivas-a-pascoa\/","title":{"rendered":"Unidades do Dease desenvolvem atividades alusivas \u00e0 Pascoa"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CONFEC\u00c7\u00c3O DE OVOS DE P\u00c1SCOA NO CASEP DE JOA\u00c7ABA&nbsp;<\/strong><\/p>\n<p style=\"text-align: justify;\">Os socioeducandos do Casep de Joa\u00e7aba, com o aux\u00edlio dos colaboradores da Unidade, produziram ovos de colher para a P\u00e1scoa deste ano.&nbsp;A atividade, dividida em tr\u00eas partes, iniciou com a produ\u00e7\u00e3o das casquinhas de chocolate. Na segunda etapa, as casquinhas foram recheadas com creme de maracuj\u00e1, brigadeiro e beijinho e finalizadas com a embalagem.<\/p>\n<p style=\"text-align: justify;\">Os ovos confeccionados ser\u00e3o distribu\u00eddos entre os socioeducandos e os colaboradores da Unidade.&nbsp;<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DECORA\u00c7\u00c3O DE P\u00c1SCOA NO CASEP DE S\u00c3O JOS\u00c9 DO CEDRO<\/strong><\/p>\n<p style=\"text-align: justify;\">Os adolescentes do Casep de S\u00e3o Jos\u00e9 do Cedro fizeram a ornamenta\u00e7\u00e3o da Unidade para a P\u00e1scoa. &nbsp;O objetivo da atividade foi mostrar para os socioeducandos os diferentes s\u00edmbolos pascais e explicar como a data \u00e9 especial e importante.<\/p>\n<p style=\"text-align: justify;\">Na atividade, produziram um mural com a frase \u201cP\u00e1scoa \u00e9 passagem, \u00e9 educa\u00e7\u00e3o, \u00e9 ajudar gente a ser mais gente, \u00e9 transformar a rotina da caminhada em esperan\u00e7a.\u201d Tamb\u00e9m foram produzidas cestas e casquinhas coloridas, que ser\u00e3o presenteadas aos familiares dos socioeducandos.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-814\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/04\/Fotos_Pascoa_SJC-b8c.jpg\" alt=\"Fotos P\u00e1scoa SJC\" width=\"597\" height=\"439\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>PROJETO P\u00c1SCOA NA SEMILIBERDADE DE CA\u00c7ADOR<\/strong><\/p>\n<p> Os adolescentes da Casa de Semiliberdade de Ca\u00e7ador participaram de atividades para o Projeto P\u00e1scoa. Eles confeccionaram guirlandas com adere\u00e7os pascais e tamb\u00e9m montaram um painel utilizando EVA, papel\u00e3o e tinta.<br \/>As produ\u00e7\u00f5es dos socioeducandos foram colocadas nas portas e paredes da Unidade.<br \/>O motivo da atividade foi desenvolver as habilidades dos adolescentes e tamb\u00e9m trabalhar a criatividade mostrando a eles o real motivo da P\u00e1scoa.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-815\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/04\/Fotos_Pascoa_Cacador-ac0.jpg\" alt=\"Fotos P\u00e1scoa Ca\u00e7ador\" width=\"563\" height=\"572\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>OFICINA DE P\u00c1SCOA NA SEMILIBERDADE DE BLUMENAU<\/strong><\/p>\n<p style=\"text-align: justify;\">Com a participa\u00e7\u00e3o dos socioeducandos, cozinheira, instrutor e educadores, a Casa de Semiliberdade de Blumenau desenvolveu atividades com motivos pascais, destacando-se a produ\u00e7\u00e3o de ovos artesanais.<\/p>\n<p style=\"text-align: justify;\">Aproveitando o momento de P\u00e1scoa&nbsp; foi feita aquisi\u00e7\u00e3o de materiais para produ\u00e7\u00e3o de ovos de chocolate e trufas, bem como, criando-se o ambiente prop\u00edcio para discutir sobre o momento Pascal.<\/p>\n<p style=\"text-align: justify;\">Atrav\u00e9s desta oficina, foi poss\u00edvel capacitar&nbsp;os adolescentes para a produ\u00e7\u00e3o de ovos de p\u00e1scoa, possibilitando o conhecimento para uma futura renda extra.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-816\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/04\/Fotos_Pascoa_Blumenau-960.jpg\" alt=\"Fotos P\u00e1scoa Blumenau\" width=\"539\" height=\"567\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>CONFEC\u00c7\u00c3O DE OVOS DE P\u00c1SCOA NO CASEP DE JOA\u00c7ABA&nbsp; Os socioeducandos do Casep de Joa\u00e7aba, com o aux\u00edlio dos colaboradores da Unidade, produziram ovos de colher para a P\u00e1scoa deste ano.&nbsp;A atividade, dividida em tr\u00eas partes, iniciou com a produ\u00e7\u00e3o das casquinhas de chocolate. Na segunda etapa, as casquinhas foram recheadas com creme de maracuj\u00e1, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:05:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/817"}],"collection":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=817"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/813"}],"wp:attachment":[{"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}